{"id":86637,"date":"2026-07-12T06:20:12","date_gmt":"2026-07-12T09:20:12","guid":{"rendered":"https:\/\/mussicom.com\/noticias\/ayrton-senna-e-reconhecido-oficialmente-como-heroi-da-patria\/"},"modified":"2026-07-12T06:20:12","modified_gmt":"2026-07-12T09:20:12","slug":"ayrton-senna-e-reconhecido-oficialmente-como-heroi-da-patria","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/ayrton-senna-e-reconhecido-oficialmente-como-heroi-da-patria\/","title":{"rendered":"Ayrton Senna \u00e9 reconhecido oficialmente como Her\u00f3i da P\u00e1tria\u00a0"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>O tricampe\u00e3o mundial de F\u00f3rmula 1 Ayrton Senna foi reconhecido oficialmente como Her\u00f3i da P\u00e1tria. A Lei 15.447\/2026\u00a0prev\u00ea a inscri\u00e7\u00e3o do nome do ex-piloto no Livro de Her\u00f3is e Hero\u00ednas da P\u00e1tria, mantido no Pante\u00e3o da P\u00e1tria, na Pra\u00e7a dos Tr\u00eas Poderes, em Bras\u00edlia.\u00a0<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1696514&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p>A legisla\u00e7\u00e3o, sancionada pelo presidente Luiz In\u00e1cio Lula da Silva, foi oriunda do Projeto de Lei 789\/2024, de autoria do senador Astronauta Marcos Pontes (PL-SP). A mat\u00e9ria teve relat\u00f3rio favor\u00e1vel do senador Jorge Kajuru (PSB-GO) e foi aprovada em decis\u00e3o terminativa pela Comiss\u00e3o de Esporte do Senado, em maio, sem necessidade de vota\u00e7\u00e3o no Plen\u00e1rio.\u00a0<\/p>\n<p>O t\u00edtulo de Her\u00f3i ou Hero\u00edna da P\u00e1tria \u00e9 uma homenagem para nomes de destaque com papel relevante na defesa ou na constru\u00e7\u00e3o do pa\u00eds e foi criado em 1992.<\/p>\n<p><strong>Ayrton Senna conquistou tr\u00eas t\u00edtulos mundiais de F\u00f3rmula 1 (1988, 1990 e 1991) e venceu 41 Grandes Pr\u00eamios ao longo da carreira.<\/strong> Em 2023, ele j\u00e1 havia sido declarado Patrono do Esporte Brasileiro.\u00a0<\/p>\n<p>Senna morreu tragicamente em um acidente no 1\u00ba de maio de 1994, aos 34 anos, durante o Grande Pr\u00eamio de San Marino, em \u00cdmola, na It\u00e1lia.<\/p>\n<p>      <!-- Relacionada --><br \/>\n            <!-- Relacionada -->\n    <\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/ayrton-senna-e-reconhecido-oficialmente-como-heroi-da-patria\">Ag\u00eancia Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tricampe\u00e3o mundial de F\u00f3rmula 1 Ayrton Senna foi reconhecido oficialmente como Her\u00f3i da P\u00e1tria. A Lei 15.447\/2026\u00a0prev\u00ea a inscri\u00e7\u00e3o do nome do ex-piloto no Livro de Her\u00f3is e Hero\u00ednas da P\u00e1tria, mantido no Pante\u00e3o da P\u00e1tria, na Pra\u00e7a dos Tr\u00eas Poderes, em Bras\u00edlia.\u00a0 A legisla\u00e7\u00e3o, sancionada pelo presidente Luiz In\u00e1cio Lula da Silva, foi [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":86638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[40],"tags":[],"class_list":["post-86637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/86637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=86637"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/86637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/86638"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=86637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=86637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=86637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}