{"id":77114,"date":"2026-05-04T19:55:56","date_gmt":"2026-05-04T22:55:56","guid":{"rendered":"https:\/\/mussicom.com\/noticias\/santos-encerra-preparacao-com-treino-tatico-e-deve-ter-retorno-de-neymar\/"},"modified":"2026-05-04T19:55:56","modified_gmt":"2026-05-04T22:55:56","slug":"santos-encerra-preparacao-com-treino-tatico-e-deve-ter-retorno-de-neymar","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/santos-encerra-preparacao-com-treino-tatico-e-deve-ter-retorno-de-neymar\/","title":{"rendered":"Santos encerra prepara\u00e7\u00e3o com treino t\u00e1tico e deve ter retorno de Neymar"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div id=\"attachment_183518\" style=\"width: 979px\" class=\"wp-caption aligncenter\"><img alt=\"\" fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-183518\" class=\"wp-image-183518\" src=\"https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-300x240.jpg\" alt=\"\" width=\"969\" height=\"775\" srcset=\"https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-177x142.jpg 177w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-200x160.jpg 200w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-300x240.jpg 300w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-400x320.jpg 400w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-600x480.jpg 600w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c-768x614.jpg 768w, https:\/\/www.diariodopeixe.com.br\/wp-content\/uploads\/2026\/05\/55248973045_5b2a4c1c83_c.jpg 800w\" sizes=\"(max-width: 969px) 100vw, 969px\"\/><\/p>\n<p id=\"caption-attachment-183518\" class=\"wp-caption-text\">Neymar deve voltar ao time titular do Santos contra o Recoleta (Cr\u00e9dito: Raul Baretta\/SantosFC)<\/p>\n<\/div>\n<p>O <strong>Santos<\/strong> finalizou, na manh\u00e3 desta segunda-feira, a prepara\u00e7\u00e3o para o confronto contra o Recoleta, pela Copa Sul-Americana. No CT Rei Pel\u00e9, o t\u00e9cnico Cuca comandou uma atividade com foco t\u00e1tico, al\u00e9m de trabalhos espec\u00edficos de bola parada.<\/p>\n<p>A principal novidade para o jogo deve ser o retorno de Neymar ao time titular, ocupando a vaga de \u00c1lvaro Barreal no setor ofensivo. A base da equipe deve ser mantida em rela\u00e7\u00e3o \u00e0s \u00faltimas partidas.<\/p>\n<p>Por outro lado, o treinador segue com uma lista de desfalques. Mayke est\u00e1 fora por conta de uma virose, enquanto Lautaro D\u00edaz ainda sente dores na coxa direita. Tamb\u00e9m seguem em recupera\u00e7\u00e3o Vin\u00edcius Lira, com les\u00e3o no joelho esquerdo, Gustavo Henrique, com problema no adutor da coxa esquerda, e Gabriel Menino, em transi\u00e7\u00e3o f\u00edsica.<\/p>\n<p>Diante desse cen\u00e1rio, um prov\u00e1vel time tem: Gabriel Braz\u00e3o; Igor Vin\u00edcius, Lucas Ver\u00edssimo, Luan Peres e Escobar; Jo\u00e3o Schmidt, Christian Oliva, Gabriel Bontempo e Rollheiser; Neymar e Gabigol.<\/p>\n<p>No primeiro turno da fase de grupos, as equipes se enfrentaram na Vila Belmiro e empataram por 1 a 1, em partida na qual o advers\u00e1rio utilizou uma forma\u00e7\u00e3o alternativa.<\/p>\n<p>O Santos chega pressionado para o duelo. Com dois pontos em tr\u00eas rodadas, a equipe ocupa a \u00faltima posi\u00e7\u00e3o do Grupo D e precisa de um resultado positivo fora de casa para seguir com chances de classifica\u00e7\u00e3o na competi\u00e7\u00e3o.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.diariodopeixe.com.br\/noticias\/santos-encerra-preparacao-com-treino-tatico-e-deve-ter-retorno-de-neymar\/\">Di\u00e1rio do Peixe<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neymar deve voltar ao time titular do Santos contra o Recoleta (Cr\u00e9dito: Raul Baretta\/SantosFC) O Santos finalizou, na manh\u00e3 desta segunda-feira, a prepara\u00e7\u00e3o para o confronto contra o Recoleta, pela Copa Sul-Americana. No CT Rei Pel\u00e9, o t\u00e9cnico Cuca comandou uma atividade com foco t\u00e1tico, al\u00e9m de trabalhos espec\u00edficos de bola parada. A principal novidade [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":77115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[55],"tags":[],"class_list":["post-77114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santos-fc"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/77114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=77114"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/77114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/77115"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=77114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=77114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=77114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}