{"id":73525,"date":"2026-04-16T13:48:30","date_gmt":"2026-04-16T16:48:30","guid":{"rendered":"https:\/\/mussicom.com\/trump-anuncia-cessar-fogo-no-libano\/"},"modified":"2026-04-16T13:48:30","modified_gmt":"2026-04-16T16:48:30","slug":"trump-anuncia-cessar-fogo-no-libano","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/trump-anuncia-cessar-fogo-no-libano\/","title":{"rendered":"Trump anuncia cessar-fogo no L\u00edbano"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"tp-post-content\">\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">O presidente dos Estados Unidos, Donald Trump, disse nesta quinta-feira (16) que foi acertado um cessar-fogo de dez dias no L\u00edbano, onde Israel enfrenta o grupo terrorista Hezbollah, aliado do Ir\u00e3, desde o come\u00e7o de mar\u00e7o.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">Em post na rede Truth Social, Trump disse que conversou com o presidente liban\u00eas, Joseph Aoun, e com o primeiro-ministro israelense, Benjamin Netanyahu.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">\u201cEsses dois l\u00edderes concordaram que, para alcan\u00e7ar a paz entre seus pa\u00edses, iniciar\u00e3o formalmente um cessar-fogo de dez dias \u00e0s 17h [hor\u00e1rio do leste dos EUA, 18h de Bras\u00edlia]\u201d, disse Trump, que lembrou da reuni\u00e3o realizada em Washington na ter\u00e7a-feira (14), na qual os americanos intermediaram conversas entre representantes dos dois pa\u00edses.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">\u201cFoi uma honra para mim resolver nove guerras ao redor do mundo, e esta ser\u00e1 a d\u00e9cima, ent\u00e3o vamos conseguir!\u201d, disse Trump. O presidente americano acrescentou, em um post separado, que convidar\u00e1 Netanyahu e Aoun para um encontro na Casa Branca.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">Israel enfrenta o Hezbollah no L\u00edbano (e n\u00e3o o ex\u00e9rcito liban\u00eas) porque o grupo terrorista iniciou ataques contra o territ\u00f3rio israelense devido \u00e0 guerra dos americanos e de Israel contra o Ir\u00e3, no momento em um cessar-fogo de duas semanas (prazo que termina na ter\u00e7a-feira, 21).<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">Na semana passada, Washington e Teer\u00e3 anunciaram um cessar-fogo de duas semanas, mas o Ir\u00e3 voltou a bloquear o estrat\u00e9gico Estreito de Ormuz porque alegou que a tr\u00e9gua foi desrespeitada com a continuidade dos ataques de Israel ao L\u00edbano. Estados Unidos e Israel afirmaram na ocasi\u00e3o que o cessar-fogo com o Ir\u00e3 n\u00e3o inclu\u00eda o L\u00edbano.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN postParagraph_post-paragraph-innerHtml__Q5vwc\">Ap\u00f3s negocia\u00e7\u00f5es com o Ir\u00e3 no Paquist\u00e3o no fim de semana n\u00e3o terem resultado num acordo, Trump anunciou que os Estados Unidos fariam seu pr\u00f3prio bloqueio de Ormuz, que entrou em vigor na segunda-feira (13).<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/mundo\/trump-anuncia-cessar-fogo-no-libano-exigencia-do-ira-para-reabrir-ormuz\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente dos Estados Unidos, Donald Trump, disse nesta quinta-feira (16) que foi acertado um cessar-fogo de dez dias no L\u00edbano, onde Israel enfrenta o grupo terrorista Hezbollah, aliado do Ir\u00e3, desde o come\u00e7o de mar\u00e7o. Em post na rede Truth Social, Trump disse que conversou com o presidente liban\u00eas, Joseph Aoun, e com o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":73526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-73525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/73525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=73525"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/73525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/73526"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=73525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=73525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=73525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}