{"id":62424,"date":"2026-02-11T09:07:32","date_gmt":"2026-02-11T12:07:32","guid":{"rendered":"https:\/\/mussicom.com\/trigo-fecha-misto-apos-ajustes-do-usda\/"},"modified":"2026-02-11T09:07:32","modified_gmt":"2026-02-11T12:07:32","slug":"trigo-fecha-misto-apos-ajustes-do-usda","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/trigo-fecha-misto-apos-ajustes-do-usda\/","title":{"rendered":"Trigo fecha misto ap\u00f3s ajustes do USDA"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>O mercado internacional de trigo encerrou a sess\u00e3o desta ter\u00e7a-feira com comportamento misto nas principais bolsas, ap\u00f3s a divulga\u00e7\u00e3o de novas estimativas de oferta e demanda do Departamento de Agricultura dos EUA (USDA). As mudan\u00e7as foram pontuais e acabaram limitando oscila\u00e7\u00f5es mais amplas nos pre\u00e7os ao longo do dia, mantendo o cen\u00e1rio de cautela entre os operadores.&#13;\n<\/p>\n<p>Em Chicago, o contrato de mar\u00e7o do trigo brando SRW fechou em baixa de 0,09%, com recuo de 0,50 cent por bushel, a 528,25 centavos de d\u00f3lar. O vencimento maio caiu 0,14%, ou 0,75 cent, encerrando a 538,00 centavos por bushel. Em Kansas, o trigo duro HRW para mar\u00e7o registrou alta de 0,33%, avan\u00e7o de 1,75 cent, cotado a 530,50 centavos por bushel. J\u00e1 em Minneapolis, o trigo HRS para mar\u00e7o terminou em queda de 0,39%, ou 2,25 centavos, a 568,25 centavos por bushel. Na Euronext, o contrato de mar\u00e7o do trigo para moagem permaneceu est\u00e1vel, a 189,50 euros por tonelada. Bolsas da Argentina, Londres e Austr\u00e1lia tamb\u00e9m divulgaram seus fechamentos.&#13;\n<\/p>\n<p>O relat\u00f3rio de oferta e demanda do USDA trouxe ajustes que ajudaram a explicar o desempenho do dia. Nos Estados Unidos, os estoques finais foram elevados para 25,34 milh\u00f5es de toneladas, o maior volume desde 2019\/20, refletindo menor consumo dom\u00e9stico. No cen\u00e1rio global, a oferta total foi levemente reduzida para 841,80 milh\u00f5es de toneladas, ap\u00f3s uma sequ\u00eancia de revis\u00f5es positivas na produ\u00e7\u00e3o em relat\u00f3rios anteriores.&#13;\n<\/p>\n<p>Com estoques americanos maiores e leve redu\u00e7\u00e3o na oferta mundial, o mercado encontrou fatores opostos, o que resultou em movimenta\u00e7\u00e3o contida e varia\u00e7\u00f5es discretas nas cota\u00e7\u00f5es ao fim do preg\u00e3o.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<\/p><\/div>\n<p><script data-cfasync=\"false\">\n    !function (f, b, e, v, n, t, s) {\n        if (f.fbq) return; n = f.fbq = function () {\n            n.callMethod ?\n                n.callMethod.apply(n, arguments) : n.queue.push(arguments)\n        };\n        if (!f._fbq) f._fbq = n; n.push = n; n.loaded = !0; n.version = '2.0';\n        n.queue = []; t = b.createElement(e); t.async = !0;\n        t.src = v; s = b.getElementsByTagName(e)[0];\n        s.parentNode.insertBefore(t, s)\n    }(window, document, 'script',\n        'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n    fbq('init', '522546078623747');\n    fbq('track', 'PageView');\n<\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.agrolink.com.br\/noticias\/trigo-fecha-misto-apos-ajustes-em-relatorio_510826.html\">AGROLINK<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mercado internacional de trigo encerrou a sess\u00e3o desta ter\u00e7a-feira com comportamento misto nas principais bolsas, ap\u00f3s a divulga\u00e7\u00e3o de novas estimativas de oferta e demanda do Departamento de Agricultura dos EUA (USDA). As mudan\u00e7as foram pontuais e acabaram limitando oscila\u00e7\u00f5es mais amplas nos pre\u00e7os ao longo do dia, mantendo o cen\u00e1rio de cautela entre [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":34908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[53],"tags":[],"class_list":["post-62424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/62424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=62424"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/62424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/34908"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=62424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=62424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=62424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}