{"id":60993,"date":"2026-02-02T19:06:16","date_gmt":"2026-02-02T22:06:16","guid":{"rendered":"https:\/\/mussicom.com\/governo-libera-mais-r-46-bi-para-pagar-saque-aniversario-do-fgts\/"},"modified":"2026-02-02T19:06:16","modified_gmt":"2026-02-02T22:06:16","slug":"governo-libera-mais-r-46-bi-para-pagar-saque-aniversario-do-fgts","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/governo-libera-mais-r-46-bi-para-pagar-saque-aniversario-do-fgts\/","title":{"rendered":"Governo libera mais R$ 4,6 bi para pagar saque-anivers\u00e1rio do FGTS"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>O governo federal libera, a partir desta segunda-feira (2), R$ 4,6 bilh\u00f5es para pagamento da segunda parcela a trabalhadores que optaram pelo saque-anivers\u00e1rio do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS).<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1676742&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p>O valor corresponde aos recursos retidos de trabalhadores que foram demitidos entre janeiro de 2020 e 20 de dezembro de 2025. De acordo com o Minist\u00e9rio do Trabalho e Emprego, o pagamento desses saldos remanescentes nesta segunda etapa beneficiar\u00e1 822,6 mil pessoas.<\/p>\n<p>Os pagamentos dos saldos remanescentes ser\u00e3o feitos at\u00e9 o dia 12 de fevereiro.<\/p>\n<p>Confira mais informa\u00e7\u00f5es sobre o assunto no <em>Rep\u00f3rter Brasil Tarde<\/em>, da <strong>TV Brasil<\/strong><\/p>\n<p><iframe title=\"Rep\u00f3rter Brasil Tarde, 02\/02\/2026\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/rnFygdrwtrQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Na primeira etapa, foram liberados tamb\u00e9m R$ 3,8 bilh\u00f5es, que beneficiaram mais de 14 milh\u00f5es de pessoas, conforme previsto em medida provis\u00f3ria publicada no dia 23 de dezembro.<\/strong><\/p>\n<p>&gt;&gt; Siga o canal da <strong>Ag\u00eancia Brasil <\/strong>no WhatsApp<\/p>\n<h2>Penaliza\u00e7\u00e3o injusta<\/h2>\n<p><strong>Em nota, o MTE lembra que a modalidade imp\u00f5e uma \u201cpenaliza\u00e7\u00e3o injusta\u201d aos trabalhadores e trabalhadoras que optam por esse formato, ao impedir o acesso aos recursos do FGTS em caso de demiss\u00e3o.<\/strong><\/p>\n<p>\u201cO saque-anivers\u00e1rio tem essa crueldade com o trabalhador e com a trabalhadora, que adere \u00e0 modalidade e fica impedido de acessar o saldo quando perde o emprego\u201d, alerta o ministro Luiz Marinho ao lembrar que o <strong>FGTS \u00e9 uma \u201cpoupan\u00e7a individual criada para amparar o trabalhador e a trabalhadora nos momentos de desemprego, mas, na pr\u00e1tica, ele n\u00e3o consegue acess\u00e1-la justamente quando mais precisa\u201d.<\/strong><\/p>\n<p>De acordo com o MTE, a maior parte dos trabalhadores ter\u00e1 os valores creditados automaticamente nas contas banc\u00e1rias previamente cadastradas no aplicativo FGTS.<\/p>\n<p>Quem n\u00e3o informou um n\u00famero de conta para o dep\u00f3sito poder\u00e1 fazer o saque por meio dos terminais de autoatendimento da Caixa; nas casas lot\u00e9ricas; ou nas unidades do CAIXA Aqui.<\/p>\n<h2>Empr\u00e9stimos banc\u00e1rios<\/h2>\n<p>Dos 14,1 milh\u00f5es de pessoas com saldo dispon\u00edvel para saque, 9,9 milh\u00f5es possuem parte dos recursos parcialmente comprometidos com empr\u00e9stimos banc\u00e1rios, \u201co que impede o recebimento do valor integral\u201d, alerta o minist\u00e9rio.<\/p>\n<p><strong>\u201cOutras 2,1 milh\u00f5es de pessoas t\u00eam o saldo totalmente comprometido, n\u00e3o havendo, portanto, valores dispon\u00edveis para saque\u201d, acrescentou.<\/strong><\/p>\n<p>O MTE informa que, desde 2020, cerca de R$ 197 bilh\u00f5es j\u00e1 foram liberados pela modalidade saque-anivers\u00e1rio.<\/p>\n<p><strong>Desse total, 40% foram destinados diretamente aos trabalhadores, enquanto 60% foram transferidos aos bancos que anteciparam os valores por meio de opera\u00e7\u00f5es de cr\u00e9dito, detalha o minist\u00e9rio.<\/strong><\/p>\n<p>Segundo a pasta, atualmente 40,3 milh\u00f5es de pessoas aderiram \u00e0 modalidade saque-anivers\u00e1rio, em um total de 130 milh\u00f5es de trabalhadores celetistas. Deste total, 28,5 milh\u00f5es possuem opera\u00e7\u00f5es de antecipa\u00e7\u00e3o de valores ativas.<\/p>\n<p>\u00a0<\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<div class=\"dnd-atom-rendered\"><!-- scald=451805:cheio_8colunas --><br \/>\n            <img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/7beXH0gRSrcEtzlEAIx15uAXyw8=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/2026\/02\/02\/infografico_saque_fgts_retido.jpeg?itok=cySlGCxA\" alt=\"infogr\u00e1fico saque fgts retido\" title=\"EBC\"\/><br \/>\n        <img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/7beXH0gRSrcEtzlEAIx15uAXyw8=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/2026\/02\/02\/infografico_saque_fgts_retido.jpeg?itok=cySlGCxA\" alt=\"infogr\u00e1fico saque fgts retido\" title=\"EBC\"\/><br \/>\n    <!-- END scald=451805 --><\/div>\n<\/div>\n<p><em>* Mat\u00e9ria alterada \u00e0s 14h17 para corre\u00e7\u00e3o de informa\u00e7\u00e3o. O valor liberado pela Caixa a partir desta segunda-feira \u00e9 de R$ 4,6 bilh\u00f5es, e n\u00e3o R$ 3,9 bilh\u00f5es, como informado anteriormente pelo banco. O n\u00famero foi corrigido pela pr\u00f3pria Caixa posteriormente.<\/em><\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-02\/governo-libera-mais-r-46-bi-para-pagar-saque-aniversario-do-fgts\">Gazeta do Povo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo federal libera, a partir desta segunda-feira (2), R$ 4,6 bilh\u00f5es para pagamento da segunda parcela a trabalhadores que optaram pelo saque-anivers\u00e1rio do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS). O valor corresponde aos recursos retidos de trabalhadores que foram demitidos entre janeiro de 2020 e 20 de dezembro de 2025. De acordo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":60994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[45],"tags":[],"class_list":["post-60993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/60993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=60993"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/60993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/60994"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=60993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=60993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=60993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}