{"id":57741,"date":"2026-01-14T23:03:23","date_gmt":"2026-01-15T02:03:23","guid":{"rendered":"https:\/\/mussicom.com\/copa-do-mundo-fifa-anuncia-locais-de-treino-e-concentracao-da-selecao\/"},"modified":"2026-01-14T23:03:23","modified_gmt":"2026-01-15T02:03:23","slug":"copa-do-mundo-fifa-anuncia-locais-de-treino-e-concentracao-da-selecao","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/copa-do-mundo-fifa-anuncia-locais-de-treino-e-concentracao-da-selecao\/","title":{"rendered":"Copa do Mundo: Fifa anuncia locais de treino e concentra\u00e7\u00e3o da sele\u00e7\u00e3o"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A Fifa, entidade m\u00e1xima do futebol mundial, confirmou nesta quarta-feira (14) que a sele\u00e7\u00e3o brasileira ficar\u00e1 hospedada e treinar\u00e1 no estado de Nova Jersey (Estados Unidos) durante a Copa do Mundo, que come\u00e7a em 11 de junho. A entidade atendeu ao pedido pr\u00e9vio da CBF que, ap\u00f3s visitas \u00e0 v\u00e1rias cidades norte-americanas, manifestou interesse pelas instala\u00e7\u00f5es em Nova Jersey. O\u00a0Brasil treinar\u00e1 no CT Columbia Park, do clube RB New York, na cidade de Morristown, e ficar\u00e1 hospedado no hotel The Ridge, em Basking Ridge. O hotel ficar\u00e1\u00a0\u00a0inteiramente reservado para a delega\u00e7\u00e3o Amarelinha.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1674966&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p>Uma das vantagens de Nova Jersey \u00e9 a proximidade do Est\u00e1dio de Nova York, palco da estreia do Brasil contra Marrocos, em 13 de junho, \u00e0s 19h (hor\u00e1rio de Bras\u00edlia), pelo Grupo C, que tem ainda Esc\u00f3cia e Haiti. Al\u00e9m disso, o tempo gasto no trajeto entre hotel e Centro de Treinamento ser\u00e1 de apenas 15 minutos.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DTf7lrXjbRG\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<\/blockquote>\n<p>Segundo <strong>nota oficial<\/strong> da CBF, a escolha dos dois locais em Nova Jersey ocorreu ap\u00f3s an\u00e1lises presenciais\u00a0realizadas nos \u00faltimos meses em \u00a0hot\u00e9is e CTs disponibilizados pela Fifa, em v\u00e1rias cidades norte-americanas, como Orlando, Seattle, Boston, Los Angeles e Nova York, entre outras. A entidade brasileira avaliou aspectos como privacidade, conforto, seguran\u00e7a e dist\u00e2ncia para os locais de treinos e jogos.<\/p>\n<p>\u201cAnalisamos v\u00e1rios aspectos. O objetivo principal era buscar melhor qualidade de gramados, hot\u00e9is, facilidades de log\u00edsticas, a menor diferen\u00e7a poss\u00edvel de fuso e outros fatores que poderiam influenciar positivamente no desempenho da sele\u00e7\u00e3o. Encontramos na regi\u00e3o de Nova York\/Nova Jersey as melhores condi\u00e7\u00f5es em todos esses itens e isso pode fazer a diferen\u00e7a numa competi\u00e7\u00e3o que \u00e9 extremamente complicada diante da grandeza do evento&#8221;, pontuou C\u00edcero Souza, gerente geral de sele\u00e7\u00f5es masculinas.<\/p>\n<p>A CBF destacou ainda que o CT Columbia tem instala\u00e7\u00f5es de \u00faltima gera\u00e7\u00e3o, \u00e1reas de treinamento, academias de gin\u00e1stica, vesti\u00e1rios e escrit\u00f3rios administrativos, com acessibilidade. Atualmente, o espa\u00e7o passa por obras para amplia\u00e7\u00e3o das estruturas e moderniza\u00e7\u00e3o de instala\u00e7\u00f5es e equipamentos.<\/p>\n<p>Antes do Mundial, a sele\u00e7\u00e3o far\u00e1 dois amistosos contra sele\u00e7\u00f5es europeias, ambos nos Estados Unidos. O escrete canarinho enfrenta a Fran\u00e7a em 26 de mar\u00e7o, \u00e0s17h, no Gillette Stadium, no estado de Massachusetts e, cinco dias depois, encara a Cro\u00e1cia, \u00e0s 21h, Camping World Stadium, na Fl\u00f3rida.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-01\/copa-do-mundo-fifa-anuncia-locais-de-treino-e-concentracao-da-selecao\">Ag\u00eancia Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Fifa, entidade m\u00e1xima do futebol mundial, confirmou nesta quarta-feira (14) que a sele\u00e7\u00e3o brasileira ficar\u00e1 hospedada e treinar\u00e1 no estado de Nova Jersey (Estados Unidos) durante a Copa do Mundo, que come\u00e7a em 11 de junho. A entidade atendeu ao pedido pr\u00e9vio da CBF que, ap\u00f3s visitas \u00e0 v\u00e1rias cidades norte-americanas, manifestou interesse pelas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":57742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[40],"tags":[],"class_list":["post-57741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/57741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=57741"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/57741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/57742"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=57741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=57741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=57741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}