{"id":57126,"date":"2025-12-24T15:04:50","date_gmt":"2025-12-24T18:04:50","guid":{"rendered":"https:\/\/mussicom.com\/loyola-acerta-base-salarial-com-o-santos-e-acordo-agora-depende-de-aval-do-independiente\/"},"modified":"2025-12-24T15:04:50","modified_gmt":"2025-12-24T18:04:50","slug":"loyola-acerta-base-salarial-com-o-santos-e-acordo-agora-depende-de-aval-do-independiente","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/loyola-acerta-base-salarial-com-o-santos-e-acordo-agora-depende-de-aval-do-independiente\/","title":{"rendered":"Loyola acerta base salarial com o Santos, e acordo agora depende de aval do Independiente"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div id=\"attachment_172961\" style=\"width: 972px\" class=\"wp-caption aligncenter\"><\/p>\n<p id=\"caption-attachment-172961\" class=\"wp-caption-text\">Santos tenta a contrata\u00e7\u00e3o de Felipe Loyola (Foto: Divulga\u00e7\u00e3o \/ Indepediente)<\/p>\n<\/div>\n<p>O Santos avan\u00e7ou nas tratativas por Felipe Loyola ap\u00f3s chegar a um acordo nos termos salariais com o jogador. A aceita\u00e7\u00e3o da base apresentada pelo clube paulista \u00e9 vista internamente como um passo relevante, j\u00e1 que permite ao Peixe concentrar esfor\u00e7os na negocia\u00e7\u00e3o com o Independiente, atual clube do atleta.<\/p>\n<p>A proposta encaminhada ao time argentino prev\u00ea o pagamento de 6 milh\u00f5es de d\u00f3lares, divididos em tr\u00eas parcelas, por 80% dos direitos econ\u00f4micos do volante. O valor agradou ao Independiente, mas a libera\u00e7\u00e3o est\u00e1 condicionada \u00e0 apresenta\u00e7\u00e3o de garantias financeiras. O clube argentino det\u00e9m 50% dos direitos do jogador e, por isso, ficaria apenas com parte do montante total da opera\u00e7\u00e3o, enquanto a outra metade pertence ao Huachipato, do Chile.<\/p>\n<p>O acerto pr\u00e9vio entre Santos e Loyola tamb\u00e9m teve impacto direto na disputa de mercado. Com o sinal positivo do atleta, o Peixe passou \u00e0 frente do Fluminense, que monitorava a situa\u00e7\u00e3o e avaliava uma investida pelo meio-campista para a pr\u00f3xima temporada.<\/p>\n<p>Titular do Independiente em 2025, Loyola tem contrato at\u00e9 2028 e soma 42 partidas e nove gols no ano, o que contribuiu para sua valoriza\u00e7\u00e3o. Al\u00e9m de atuar como volante, o jogador tamb\u00e9m pode ser utilizado na lateral-direita, caracter\u00edstica considerada \u00fatil dentro do planejamento santista para 2026.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.diariodopeixe.com.br\/noticias\/loyola-acerta-base-salarial-com-o-santos-e-acordo-agora-depende-de-aval-do-independiente\/\">Placar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santos tenta a contrata\u00e7\u00e3o de Felipe Loyola (Foto: Divulga\u00e7\u00e3o \/ Indepediente) O Santos avan\u00e7ou nas tratativas por Felipe Loyola ap\u00f3s chegar a um acordo nos termos salariais com o jogador. A aceita\u00e7\u00e3o da base apresentada pelo clube paulista \u00e9 vista internamente como um passo relevante, j\u00e1 que permite ao Peixe concentrar esfor\u00e7os na negocia\u00e7\u00e3o com [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":40598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[55],"tags":[],"class_list":["post-57126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santos-fc"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/57126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=57126"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/57126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/40598"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=57126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=57126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=57126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}