{"id":47997,"date":"2025-10-07T10:05:20","date_gmt":"2025-10-07T13:05:20","guid":{"rendered":"https:\/\/mussicom.com\/trump-poe-fim-aos-contatos-diplomaticos-com-venezuela-diz-jornal\/"},"modified":"2025-10-07T10:05:20","modified_gmt":"2025-10-07T13:05:20","slug":"trump-poe-fim-aos-contatos-diplomaticos-com-venezuela-diz-jornal","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/trump-poe-fim-aos-contatos-diplomaticos-com-venezuela-diz-jornal\/","title":{"rendered":"Trump p\u00f5e fim aos contatos diplom\u00e1ticos com Venezuela, diz jornal"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">O presidente dos Estados Unidos, Donald Trump, cancelou os esfor\u00e7os diplom\u00e1ticos para chegar a um acordo com a Venezuela e instruiu seu enviado especial, Richard Grenell, a interromper qualquer aproxima\u00e7\u00e3o, segundo informou o jornal <em>The New York Times<\/em>.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">A decis\u00e3o do republicano p\u00f5e fim \u00e0s negocia\u00e7\u00f5es que Grenell mantinha com o regime venezuelano, destinadas a explorar poss\u00edveis acordos entre os pa\u00edses, de acordo com as fontes citadas pelo jornal.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">A publica\u00e7\u00e3o diz que a ordem presidencial foi comunicada diretamente por Trump a Grenell e ser\u00e1 aplicada de imediato, interrompendo qualquer iniciativa diplom\u00e1tica em curso com o pa\u00eds sul-americano. A decis\u00e3o marca uma mudan\u00e7a significativa na pol\u00edtica da Casa Branca em rela\u00e7\u00e3o \u00e0 Venezuela.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Os EUA mant\u00eam no Caribe ao menos oito navios de guerra e um submarino de ataque r\u00e1pido de propuls\u00e3o nuclear, assim como mais de 4.500 militares, sob o argumento de combate ao narcotr\u00e1fico. Em contrapartida, o ditador da Venezuela, Nicol\u00e1s Maduro, alega que se trata de uma tentativa para propiciar &#8220;uma mudan\u00e7a de regime&#8221; e impor &#8220;governos fantoches&#8221; em seu pa\u00eds.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Desde agosto, as for\u00e7as americanas destru\u00edram ao menos cinco embarca\u00e7\u00f5es vinculadas ao narcotr\u00e1fico, segundo Washington. Al\u00e9m disso, Trump declarou que os EUA est\u00e3o em um &#8220;conflito armado n\u00e3o internacional&#8221; com os cart\u00e9is de drogas, justificando assim os ataques.<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/mundo\/trump-cancela-contatos-diplomaticos-venezuela-diz-jornal\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente dos Estados Unidos, Donald Trump, cancelou os esfor\u00e7os diplom\u00e1ticos para chegar a um acordo com a Venezuela e instruiu seu enviado especial, Richard Grenell, a interromper qualquer aproxima\u00e7\u00e3o, segundo informou o jornal The New York Times. A decis\u00e3o do republicano p\u00f5e fim \u00e0s negocia\u00e7\u00f5es que Grenell mantinha com o regime venezuelano, destinadas a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":44957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-47997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/47997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=47997"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/47997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/44957"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=47997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=47997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=47997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}