{"id":45222,"date":"2025-09-23T00:18:20","date_gmt":"2025-09-23T03:18:20","guid":{"rendered":"https:\/\/mussicom.com\/o-filme-brasileiro-que-e-incrivelmente-preciso-e-comovente-segundo-walter-salles\/"},"modified":"2025-09-23T00:18:20","modified_gmt":"2025-09-23T03:18:20","slug":"o-filme-brasileiro-que-e-incrivelmente-preciso-e-comovente-segundo-walter-salles","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/o-filme-brasileiro-que-e-incrivelmente-preciso-e-comovente-segundo-walter-salles\/","title":{"rendered":"O filme brasileiro que \u00e9 \u2018incrivelmente preciso e comovente\u2019, segundo Walter Salles"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p data-start=\"155\" data-end=\"459\">O cineasta<strong> Walter Salles<\/strong>, respons\u00e1vel por t\u00edtulos marcantes como <strong><em data-start=\"220\" data-end=\"239\">Central do Brasil<\/em> <\/strong>e <strong><em data-start=\"242\" data-end=\"266\">Ainda Estou Aqui<\/em><\/strong>, destacou uma obra brasileira entre seus filmes essenciais. Em entrevista ao Letterboxd, ele elegeu <strong><em data-start=\"361\" data-end=\"374\">Vidas Secas<\/em><\/strong> (1963), de<strong> Nelson Pereira dos Santos<\/strong>, como um dos trabalhos que mais o impactaram.<\/p>\n<p data-start=\"461\" data-end=\"845\">Baseado no cl\u00e1ssico hom\u00f4nimo de <strong>Graciliano Ramos<\/strong>, o longa retrata a dura trajet\u00f3ria de uma fam\u00edlia nordestina que enfrenta a seca e a mis\u00e9ria em busca de sobreviv\u00eancia. Para Salles, a for\u00e7a do filme est\u00e1 justamente em sua sobriedade e precis\u00e3o narrativa.<\/p>\n<blockquote>\n<p data-start=\"461\" data-end=\"845\">\u201c\u00c9 uma adapta\u00e7\u00e3o extraordin\u00e1ria. N\u00e3o h\u00e1 um plano a mais, cada escolha \u00e9 incrivelmente precisa e comovente\u201d, afirmou o cineasta.<\/p>\n<\/blockquote>\n<p data-start=\"847\" data-end=\"1062\"><strong>Salles<\/strong> tamb\u00e9m ressaltou como a obra continua atual, tanto pelo retrato social quanto pela linguagem cinematogr\u00e1fica. <strong>\u201c\u00c9 um filme contido, mas devastador, que segue tocando profundamente quem o assiste\u201d<\/strong>, completou.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Four Favorites with I\u2019m Still Here director Walter Salles \ud83c\udde7\ud83c\uddf7<\/p>\n<p>I\u2019m Still Here is nominated for Best International Feature Film, Best Actress (Fernanda Torres) and Best Picture at the 97th Academy Awards. <a href=\"https:\/\/t.co\/uXZJxSU6xp\">pic.twitter.com\/uXZJxSU6xp<\/a><\/p>\n<p>\u2014 Letterboxd (@letterboxd) <a href=\"https:\/\/twitter.com\/letterboxd\/status\/1890430919120400456?ref_src=twsrc%5Etfw\">February 14, 2025<\/a><\/p>\n<\/blockquote>\n<p data-start=\"847\" data-end=\"1062\"><strong>LEIA TAMB\u00c9M: 5 filmes que voc\u00ea (provavelmente) n\u00e3o sabia que eram contos de Stephen King<\/strong><\/p>\n<div id=\"polls-15-loading\" class=\"wp-polls-loading\">\u00a0Loading &#8230;<\/div>\n<div class=\"author-box clearfix mb-4\">\n<div class=\"d-flex align-items-center\">\n<div class=\"author-avatar\">\n        &#13;<br \/>\n          <img decoding=\"async\" alt=\"Giulia Cardoso (@agiuliacardoso)\" src=\"https:\/\/rollingstone.com.br\/wp-content\/uploads\/2025\/09\/giulia.jpeg\" class=\"avatar avatar-115 photo rounded-circle\" height=\"115\" width=\"115\"\/>\n      <\/div>\n<div class=\"author-info ms-3\">\n<p>Jornalista em forma\u00e7\u00e3o pela Universidade Cruzeiro do Sul, em S\u00e3o Paulo, Giulia Cardoso come\u00e7ou em 2020 como volunt\u00e1ria em portais de cinema. J\u00e1 foi estagi\u00e1ria na Perifacon e agora trabalha no n\u00facleo de cinema da Editora Perfil, que inclui CineBuzz, Rolling Stone Brasil e Contigo.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/rollingstone.com.br\/cinema\/o-filme-brasileiro-que-e-incrivelmente-preciso-e-comovente-segundo-walter-salles\/\">rollingstone.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cineasta Walter Salles, respons\u00e1vel por t\u00edtulos marcantes como Central do Brasil e Ainda Estou Aqui, destacou uma obra brasileira entre seus filmes essenciais. Em entrevista ao Letterboxd, ele elegeu Vidas Secas (1963), de Nelson Pereira dos Santos, como um dos trabalhos que mais o impactaram. Baseado no cl\u00e1ssico hom\u00f4nimo de Graciliano Ramos, o longa [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":45223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[51],"tags":[],"class_list":["post-45222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/45222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=45222"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/45222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/45223"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=45222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=45222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=45222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}