{"id":43565,"date":"2025-09-13T05:06:35","date_gmt":"2025-09-13T08:06:35","guid":{"rendered":"https:\/\/mussicom.com\/subsecretario-dos-eua-critica-condenacao-de-bolsonaro\/"},"modified":"2025-09-13T05:06:35","modified_gmt":"2025-09-13T08:06:35","slug":"subsecretario-dos-eua-critica-condenacao-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/subsecretario-dos-eua-critica-condenacao-de-bolsonaro\/","title":{"rendered":"Subsecret\u00e1rio dos EUA critica condena\u00e7\u00e3o de Bolsonaro"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"postParagraph_post-paragraph__juWZN\">O subsecret\u00e1rio de Estado americano para a Diplomacia P\u00fablica, Darren Beattie, disse nesta sexta-feira (12) que a condena\u00e7\u00e3o judicial do ex-presidente Jair Bolsonaro \u00e9 um \u201cnovo marco\u201d no \u201ccomplexo de censura\u201d no Brasil.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Na quinta-feira (11), a Primeira Turma do Supremo Tribunal Federal (STF) condenou Bolsonaro a 27 anos e 3 meses de pris\u00e3o por acusa\u00e7\u00f5es de tentativa de golpe de Estado ap\u00f3s a elei\u00e7\u00e3o de 2022.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">\u201cOntem, quatro dos cinco ministros da suprema corte do Brasil votaram pela condena\u00e7\u00e3o do ex-presidente Jair Bolsonaro a 27 anos de pris\u00e3o\u201d, escreveu Beattie em post no X, cometendo dois pequenos equ\u00edvocos: o STF tem 11 ministros e cinco \u00e9 apenas o n\u00famero de magistrados da Primeira Turma do tribunal; e nem todos os cinco ju\u00edzes da Primeira Turma votaram ontem, quando ocorreram apenas os votos de C\u00e1rmen L\u00facia e Cristiano Zanin \u2013 os demais haviam votado na ter\u00e7a (9) e na quarta-feira (10).<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">\u201cEsta decis\u00e3o representa um novo marco fat\u00eddico no complexo de censura e persegui\u00e7\u00e3o do sancionado juiz [do STF, Alexandre de] Moraes, violador de direitos humanos, que tem como alvo Bolsonaro e seus apoiadores. Encaramos este acontecimento sombrio com a m\u00e1xima seriedade\u201d, disse o subsecret\u00e1rio.<\/p>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">Ontem, logo ap\u00f3s a confirma\u00e7\u00e3o da condena\u00e7\u00e3o de Bolsonaro, o secret\u00e1rio de Estado americano, Marco Rubio, disse no X que Washington responder\u00e1 \u201cde forma adequada\u201d, mas novas medidas contra Moraes e o Brasil ainda n\u00e3o foram anunciadas.<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/mundo\/subsecretario-dos-eua-critica-condenacao-de-bolsonaro\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O subsecret\u00e1rio de Estado americano para a Diplomacia P\u00fablica, Darren Beattie, disse nesta sexta-feira (12) que a condena\u00e7\u00e3o judicial do ex-presidente Jair Bolsonaro \u00e9 um \u201cnovo marco\u201d no \u201ccomplexo de censura\u201d no Brasil. Na quinta-feira (11), a Primeira Turma do Supremo Tribunal Federal (STF) condenou Bolsonaro a 27 anos e 3 meses de pris\u00e3o por [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":43566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-43565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/43565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=43565"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/43565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/43566"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=43565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=43565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=43565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}