{"id":41267,"date":"2025-09-01T23:06:26","date_gmt":"2025-09-02T02:06:26","guid":{"rendered":"https:\/\/mussicom.com\/pgr-defende-prisao-de-braga-netto-em-manifestacao-ao-stf\/"},"modified":"2025-09-01T23:06:26","modified_gmt":"2025-09-02T02:06:26","slug":"pgr-defende-prisao-de-braga-netto-em-manifestacao-ao-stf","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/pgr-defende-prisao-de-braga-netto-em-manifestacao-ao-stf\/","title":{"rendered":"PGR defende pris\u00e3o de Braga Netto em manifesta\u00e7\u00e3o ao STF"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"postParagraph_post-paragraph__juWZN\">A Procuradoria-Geral da Rep\u00fablica (PGR) manifestou-se pela manuten\u00e7\u00e3o da pris\u00e3o de Walter Braga Netto, general da reserva e ex-candidato a vice-presidente na chapa de Jair Bolsonaro (PL) em 2022.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">O parecer foi enviado ao Supremo Tribunal Federal (STF) pelo procurador-geral da Rep\u00fablica, Paulo Gonet, que se posicionou contr\u00e1rio ao mais recente pedido de soltura apresentado pela defesa de Braga Netto. Segundo a PGR, n\u00e3o surgiram fatos novos que justifiquem mudan\u00e7as na situa\u00e7\u00e3o do r\u00e9u.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Braga Netto est\u00e1 detido desde dezembro do ano passado, sob acusa\u00e7\u00e3o de tentar obstruir investiga\u00e7\u00f5es referentes \u00e0 tentativa de impedir a posse do presidente Luiz In\u00e1cio Lula da Silva (PT).<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">O militar \u00e9 considerado um dos principais integrantes do suposto n\u00facleo golpista investigado pela Pol\u00edcia Federal e responde como r\u00e9u em a\u00e7\u00e3o penal sob an\u00e1lise do STF e que come\u00e7a a ser julgada nesta ter\u00e7a-feira (2).<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">O ministro Alexandre de Moraes, relator do caso no Supremo, j\u00e1 havia negado pedidos anteriores de soltura apresentados pela defesa de Braga Netto. Na decis\u00e3o que manteve o general preso, Moraes destacou a exist\u00eancia de ind\u00edcios da participa\u00e7\u00e3o do militar na suposta tentativa de golpe de Estado durante o governo Bolsonaro.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">A defesa de Braga Netto recorreu novamente da decis\u00e3o de Moraes e apresentou novo pedido de liberdade. Os advogados argumentam que a justificativa utilizada pelo ministro para diferenciar a situa\u00e7\u00e3o de Braga Netto da de Bolsonaro n\u00e3o se sustenta.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Segundo a defesa, faltam fundamentos concretos para manter a pris\u00e3o provis\u00f3ria, e o princ\u00edpio da isonomia n\u00e3o estaria sendo respeitado na compara\u00e7\u00e3o entre os dois ex-integrantes do governo federal. Os advogados alegam ainda que a justificativa firmada para manter a cust\u00f3dia \u00e9, no entendimento da defesa, inadequada e insuficiente.<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/republica\/pgr-defende-prisao-braga-netto\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Procuradoria-Geral da Rep\u00fablica (PGR) manifestou-se pela manuten\u00e7\u00e3o da pris\u00e3o de Walter Braga Netto, general da reserva e ex-candidato a vice-presidente na chapa de Jair Bolsonaro (PL) em 2022. O parecer foi enviado ao Supremo Tribunal Federal (STF) pelo procurador-geral da Rep\u00fablica, Paulo Gonet, que se posicionou contr\u00e1rio ao mais recente pedido de soltura apresentado [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":41268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-41267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/41267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=41267"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/41267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/41268"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=41267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=41267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=41267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}