{"id":40451,"date":"2025-08-28T11:20:06","date_gmt":"2025-08-28T14:20:06","guid":{"rendered":"https:\/\/mussicom.com\/camara-aprova-credito-para-energia-solar-na-agricultura\/"},"modified":"2025-08-28T11:20:06","modified_gmt":"2025-08-28T14:20:06","slug":"camara-aprova-credito-para-energia-solar-na-agricultura","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/camara-aprova-credito-para-energia-solar-na-agricultura\/","title":{"rendered":"C\u00e2mara aprova cr\u00e9dito para energia solar na agricultura"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p style=\"text-align:justify\">A C\u00e2mara dos Deputados aprovou projeto de lei que reserva recursos de garantia para opera\u00e7\u00f5es de cr\u00e9dito de cooperativas de gera\u00e7\u00e3o compartilhada de energia fotovoltaica a ser usada na produ\u00e7\u00e3o rural. A proposta tamb\u00e9m cria os programas nacionais de Florestas Produtivas de Desenvolvimento e de Sistemas Agroflorestais de Base Agroecol\u00f3gica.&#13;\n<\/p>\n<p style=\"text-align:justify\">A cria\u00e7\u00e3o dos dois programas foi inclu\u00edda pelo relator de Plen\u00e1rio, deputado Nilto Tatto (PT-SP), no Projeto de Lei 1707\/24. A proposta, do deputado Pedro Uczai (PT-SC), tratava originalmente apenas das cooperativas. O texto segue para o Senado.\u00a0De acordo com o <span class=\"termoGlossario\" contenteditable=\"false\" data-original-title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" data-placement=\"top\" data-toggle=\"tooltip\" id=\"4098\" title=\"\">substitutivo<\/span> aprovado, por 18 meses a partir da futura lei, o Fundo Garantidor de Opera\u00e7\u00f5es (FGO) reservar\u00e1 R$ 400 milh\u00f5es para garantir financiamentos de projetos de gera\u00e7\u00e3o compartilhada dessas cooperativas.<\/p>\n<p style=\"text-align:justify\">Os projetos dever\u00e3o contar com um percentual m\u00ednimo de conte\u00fado nacional definido em regulamento. A garantia do empr\u00e9stimo ser\u00e1 articulada com os programas federais relacionados \u00e0s pol\u00edticas industriais, de transi\u00e7\u00e3o energ\u00e9tica e descarboniza\u00e7\u00e3o.<\/p>\n<p style=\"text-align:justify\">J\u00e1 o dinheiro para o empr\u00e9stimo a essas cooperativas de gera\u00e7\u00e3o compartilhada poder\u00e1 vir do cr\u00e9dito rural do <span class=\"termoGlossario\" contenteditable=\"false\" data-original-title=\"Criado em 1995, o Programa Nacional de Fortalecimento da Agricultura Familiar (Pronaf) financia projetos individuais ou coletivos que gerem renda aos agricultores familiares e assentados da reforma agr\u00e1ria. O cr\u00e9dito pode ser utilizado para custeio de safra ou atividade agroindustrial, equipamentos ou infraestrutura de produ\u00e7\u00e3o e servi\u00e7os agropecu\u00e1rios ou n\u00e3o agropecu\u00e1rios. O programa possui as mais baixas taxas de juros dos financiamentos rurais.\" data-placement=\"top\" data-toggle=\"tooltip\" id=\"4314\" title=\"\">Pronaf<\/span>, condicionado ao uso da totalidade da energia gerada \u00e0s atividades de produ\u00e7\u00e3o agropecu\u00e1ria dos estabelecimentos rurais associados. Caber\u00e1 ao Conselho Monet\u00e1rio Nacional (CMN) definir as condi\u00e7\u00f5es dos financiamentos.<\/p>\n<p style=\"text-align:justify\">O autor do projeto, deputado Pedro Uczai, destacou que o objetivo \u00e9 garantir a agricultores familiares sua pr\u00f3pria cooperativa de energia solar.<\/p>\n<p style=\"text-align:justify\">J\u00e1 o deputado Nilto Tatto afirmou que a proposta contribui para acelerar a implanta\u00e7\u00e3o de usinas de menor porte, descentralizando a produ\u00e7\u00e3o de energia, ampliando a participa\u00e7\u00e3o social no setor el\u00e9trico e promovendo a democratiza\u00e7\u00e3o do acesso \u00e0 energia renov\u00e1vel.<\/p>\n<p style=\"text-align:justify\">&#8220;A iniciativa alinha-se plenamente \u00e0 estrat\u00e9gia de transi\u00e7\u00e3o energ\u00e9tica justa e inclusiva, ao mesmo tempo em que estimula o desenvolvimento regional e a sustentabilidade econ\u00f4mica dos produtores organizados em regime cooperativo&#8221;, disse.<\/p>\n<p style=\"text-align:justify\">Segundo Tatto, o projeto contempla agricultores que atualmente n\u00e3o t\u00eam pol\u00edtica de apoio para produzir energia. &#8220;Cria uma alternativa de baratear o que est\u00e1 produzindo e gerar renda com produ\u00e7\u00e3o de energia&#8221;, afirmou.<\/p>\n<p style=\"text-align:justify\">Sobre a cria\u00e7\u00e3o dos programas de Sistemas Agroflorestais (Prosafs) e de Florestas Produtivas, Nilto Tatto explicou que as iniciativas t\u00eam articula\u00e7\u00e3o direta com a pol\u00edtica energ\u00e9tica nacional. &#8220;Esses programas possibilitam a integra\u00e7\u00e3o entre produ\u00e7\u00e3o agr\u00edcola, preserva\u00e7\u00e3o ambiental e gera\u00e7\u00e3o de energia renov\u00e1vel, sobretudo pelo aproveitamento sustent\u00e1vel dos recursos florestais&#8221;, informou.<\/p>\n<p style=\"text-align:justify\"><strong>Programa agroflorestal<\/strong><br \/>&#13;<br \/>\nInclu\u00eddo no projeto, o Programa Nacional de Desenvolvimento de Sistemas Agroflorestais de Base Agroecol\u00f3gica (Prosaf) pretende promover a conserva\u00e7\u00e3o da biodiversidade dos ecossistemas e melhorar a viabilidade econ\u00f4mica dos agricultores familiares rumo a uma agricultura resiliente \u00e0 mudan\u00e7a do clima, com diversifica\u00e7\u00e3o ecol\u00f3gica, cultural e agron\u00f4mica por meio da produ\u00e7\u00e3o sustentada.<\/p>\n<p style=\"text-align:justify\">Entre os objetivos do Prosaf est\u00e3o a implanta\u00e7\u00e3o de sistemas agroflorestais de base agroecol\u00f3gica em todas as regi\u00f5es do Pa\u00eds; a recupera\u00e7\u00e3o de \u00e1reas degradadas, prioritariamente aquelas situadas em bacias hidrogr\u00e1ficas em estado cr\u00edtico e \u00e1reas consideradas inaptas aos cultivos anuais; e a expans\u00e3o, conserva\u00e7\u00e3o e manejo da cobertura florestal dos biomas brasileiros.&#13;\n<\/p>\n<p style=\"text-align:justify\">O programa tamb\u00e9m apoiar\u00e1 projetos de redes de coleta e resgate de sementes e de gen\u00e9tica animal e de produ\u00e7\u00e3o de mudas de esp\u00e9cies nativas, com \u00eanfase na agricultura familiar, comunidades tradicionais, ind\u00edgenas e quilombolas.<\/p>\n<p style=\"text-align:justify\">A prioridade do programa ser\u00e1 exatamente para os agricultores familiares, assentados da reforma agr\u00e1ria, povos e comunidades tradicionais e agricultores do meio urbano.<\/p>\n<p style=\"text-align:justify\"><strong>Conselho e comit\u00ea<\/strong><br \/>&#13;<br \/>\nPara viabilizar o funcionamento do Prosaf, o projeto prev\u00ea a exist\u00eancia de uma unidade de gerenciamento, de um conselho orientador e de um comit\u00ea t\u00e9cnico.<br \/>&#13;<br \/>\nA unidade de gerenciamento dever\u00e1 elaborar um plano operacional do programa, com metas anuais, volumes de recursos a serem aplicados e resultados a serem alcan\u00e7ados.<\/p>\n<p style=\"text-align:justify\">J\u00e1 o conselho dever\u00e1 estabelecer as diretrizes e crit\u00e9rios para a implementa\u00e7\u00e3o do plano e aprov\u00e1-lo, al\u00e9m de acompanhar a execu\u00e7\u00e3o e aprovar o relat\u00f3rio anual de atividades do programa.<\/p>\n<p style=\"text-align:justify\">Caber\u00e1 ao comit\u00ea t\u00e9cnico elaborar um manual t\u00e9cnico com diretrizes e recomenda\u00e7\u00f5es para o planejamento, a implanta\u00e7\u00e3o e monitoramento de sistemas agroflorestais de base agroecol\u00f3gica. Tamb\u00e9m dever\u00e1 desenvolver metodologia para a valora\u00e7\u00e3o de servi\u00e7os ambientais e ecossist\u00eamicos associados aos sistemas agroflorestais previstos no projeto.<\/p>\n<p style=\"text-align:justify\"><strong>Identifica\u00e7\u00e3o<\/strong><br \/>&#13;<br \/>\nPor meio de um Sistema de Identifica\u00e7\u00e3o e Valoriza\u00e7\u00e3o de Sistemas Agroflorestais de Base Agroecol\u00f3gica, dever\u00e3o ser habilitados os sistemas agroflorestais de base agroecol\u00f3gica que participar\u00e3o do programa, inclusive para a produ\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos madeir\u00e1veis de esp\u00e9cies nativas e de esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o, promovendo sua conserva\u00e7\u00e3o.<\/p>\n<p style=\"text-align:justify\">Esse sistema incentivar\u00e1 iniciativas de identifica\u00e7\u00e3o geogr\u00e1fica, identifica\u00e7\u00e3o de origem e sistemas participativos de garantia e certifica\u00e7\u00e3o agroflorestal, seja por meio de entidades p\u00fablicas ou privadas credenciadas.<\/p>\n<p style=\"text-align:justify\">Quanto \u00e0 certifica\u00e7\u00e3o, ser\u00e1 estimulada a regulariza\u00e7\u00e3o ambiental de sistemas agroflorestais de base agroecol\u00f3gica junto aos \u00f3rg\u00e3os ambientais, inclusive para a celeridade de vistorias e emiss\u00e3o de autoriza\u00e7\u00f5es de corte, de transporte e de comercializa\u00e7\u00e3o de produtos de esp\u00e9cies nativas madeir\u00e1veis e de esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o.<\/p>\n<p style=\"text-align:justify\"><strong>Financiamento<\/strong><br \/>&#13;<br \/>\nO programa ser\u00e1 financiado com recursos do Or\u00e7amento da Uni\u00e3o. Por cinco anos, seguindo regra da Lei de Diretrizes Or\u00e7ament\u00e1rias (<span class=\"termoGlossario\" contenteditable=\"false\" data-original-title=\"Lei que orienta a elabora\u00e7\u00e3o do or\u00e7amento do ano seguinte. Cont\u00e9m informa\u00e7\u00f5es sobre as metas e prioridades dos tr\u00eas poderes (Executivo, Legislativo e Judici\u00e1rio) e do Minist\u00e9rio P\u00fablico da Uni\u00e3o. Tamb\u00e9m define a meta fiscal para o ano seguinte. \u00c9 elaborada pelo Executivo e aprovada pelo Congresso Nacional.\" data-placement=\"top\" data-toggle=\"tooltip\" id=\"4066\" title=\"\">LDO<\/span>), poder\u00e1 ser usado dinheiro da convers\u00e3o de multas em servi\u00e7os ambientais, do Pronaf, do Fundo Nacional sobre Mudan\u00e7a do Clima, do Fundo Nacional do Meio Ambiente e de fundos constitucionais de desenvolvimento regional.<\/p>\n<p style=\"text-align:justify\"><strong>Florestas produtivas<\/strong><br \/>&#13;<br \/>\nEm rela\u00e7\u00e3o ao Programa Nacional de Florestas Produtivas, o objetivo \u00e9 recuperar \u00e1reas que foram alteradas ou degradadas para fins produtivos, a fim de adequ\u00e1-las para regulariza\u00e7\u00e3o ambiental por meio da agricultura familiar e amplia\u00e7\u00e3o da capacidade de produ\u00e7\u00e3o de alimentos saud\u00e1veis e de produtos da sociobiodiversidade.&#13;\n<\/p>\n<p style=\"text-align:justify\">Entre as a\u00e7\u00f5es previstas est\u00e3o:<\/p>\n<p style=\"text-align:justify\">No bioma Amaz\u00f4nia, os investimentos no programa considerar\u00e3o os munic\u00edpios priorit\u00e1rios definidos no Decreto 11.687\/23 para as a\u00e7\u00f5es de preven\u00e7\u00e3o, monitoramento, controle e redu\u00e7\u00e3o de desmatamentos e degrada\u00e7\u00e3o florestal.<\/p>\n<p style=\"text-align:justify\"><strong>Governan\u00e7a e recursos<\/strong><br \/>&#13;<br \/>\nAto conjunto dos minist\u00e9rios do Desenvolvimento Agr\u00e1rio e Agricultura Familiar; e do Meio Ambiente e Mudan\u00e7a do Clima definir\u00e1 o colegiado gestor do programa e suas compet\u00eancias.<\/p>\n<p style=\"text-align:justify\">J\u00e1 os recursos para financiar as a\u00e7\u00f5es vir\u00e3o do Or\u00e7amento da Uni\u00e3o ou de outros \u00f3rg\u00e3os e entidades, p\u00fablicas ou privadas, inclusive por meio de parcerias com organismos internacionais.<\/p>\n<p style=\"text-align:justify\"><strong>Debate em Plen\u00e1rio<\/strong><br \/>&#13;<br \/>\nDurante o debate em Plen\u00e1rio, o deputado Gilson Marques (Novo-SC) disse estar preocupado com a possibilidade de os pequenos produtores beneficiados substitu\u00edrem suas produ\u00e7\u00f5es por pequenas usinas. Al\u00e9m disso, ele avaliou que a pol\u00edtica p\u00fablica \u00e9 gen\u00e9rica e pode ter direcionamento eleitoral. &#8220;Alguns estados ser\u00e3o mais beneficiados do que outros, e a conta \u00e9 paga desproporcionalmente pelos estados&#8221;, declarou.<\/p>\n<p style=\"text-align:justify\">Em resposta, o autor do projeto, Pedro Uczai, rebateu a fala de que os recursos ser\u00e3o distribu\u00eddos de forma arbitr\u00e1ria pelos estados. &#8220;N\u00e3o tem nenhum recurso distribu\u00eddo gratuitamente. Todos s\u00e3o financiamentos, dentro das regras do Conselho Monet\u00e1rio Nacional&#8221;, explicou.<\/p>\n<p style=\"text-align:justify\">J\u00e1 o deputado Carlos Jordy (PL-RJ), vice-l\u00edder da oposi\u00e7\u00e3o, criticou a inclus\u00e3o dos sistemas agroflorestais e de florestas produtivas na proposta. &#8220;O projeto original n\u00e3o continha esse tipo de mat\u00e9rias, feitas para garantir novos programas para beneficiar assentados da reforma agr\u00e1ria e movimentos sociais em ano de elei\u00e7\u00e3o&#8221;, reclamou.<\/p>\n<p style=\"text-align:justify\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/p>\n<p style=\"text-align:justify\">Reportagem \u2013 Eduardo Piovesan e Tiago Miranda<br \/>&#13;<br \/>\nEdi\u00e7\u00e3o \u2013 Pierre Triboli<\/p>\n<\/p><\/div>\n<p><script data-cfasync=\"false\">\n    !function (f, b, e, v, n, t, s) {\n        if (f.fbq) return; n = f.fbq = function () {\n            n.callMethod ?\n                n.callMethod.apply(n, arguments) : n.queue.push(arguments)\n        };\n        if (!f._fbq) f._fbq = n; n.push = n; n.loaded = !0; n.version = '2.0';\n        n.queue = []; t = b.createElement(e); t.async = !0;\n        t.src = v; s = b.getElementsByTagName(e)[0];\n        s.parentNode.insertBefore(t, s)\n    }(window, document, 'script',\n        'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n    fbq('init', '522546078623747');\n    fbq('track', 'PageView');\n<\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.agrolink.com.br\/noticias\/camara-aprova-projeto-que-facilita-credito-para-agricultor-familiar-investir-em-energia-solar_505394.html\">AGROLINK<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados aprovou projeto de lei que reserva recursos de garantia para opera\u00e7\u00f5es de cr\u00e9dito de cooperativas de gera\u00e7\u00e3o compartilhada de energia fotovoltaica a ser usada na produ\u00e7\u00e3o rural. A proposta tamb\u00e9m cria os programas nacionais de Florestas Produtivas de Desenvolvimento e de Sistemas Agroflorestais de Base Agroecol\u00f3gica.&#13; A cria\u00e7\u00e3o dos dois programas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":40452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[53],"tags":[],"class_list":["post-40451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/40451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=40451"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/40451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/40452"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=40451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=40451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=40451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}