{"id":36660,"date":"2025-08-13T02:48:34","date_gmt":"2025-08-13T05:48:34","guid":{"rendered":"https:\/\/mussicom.com\/esmagamento-de-soja-bate-recorde-em-julho\/"},"modified":"2025-08-13T02:48:34","modified_gmt":"2025-08-13T05:48:34","slug":"esmagamento-de-soja-bate-recorde-em-julho","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/esmagamento-de-soja-bate-recorde-em-julho\/","title":{"rendered":"esmagamento de soja bate recorde em julho"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div class=\"row\">\n<div class=\"col-lg col-infos mt-0 mt-lg-0\">\n<div class=\"section-sub-title\">\n<p itemprop=\"description\">&#13;<br \/>\n                                Demanda por \u00f3leo eleva esmagamento de soja&#13;\n                            <\/p>\n<\/p><\/div>\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg p-0\">\n<div>\n<div class=\"block-news-main-infos mt-3 text-start\">\n<p>                                            <strong class=\"fn\" itemprop=\"author\" style=\"color: rgb(112, 112, 112); \">&#13;<br \/>\n                                                Agrolink&#13;<br \/>\n&#13;<br \/>\n                                                    &#8211; Seane Lennon&#13;<br \/>\n&#13;<br \/>\n                                            <\/strong><br \/>\n                                        <\/p>\n<p>                                            <abbr><time datetime=\"2025-08-12T16:41\" itemprop=\"datePublished dateModified\">Publicado em 12\/08\/2025 \u00e0s 16:41h.<\/time><\/abbr><br \/>\n                                            <\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-lg p-0 text-lg-end\">\n<div>\n<div id=\"mdEnviarPagina\" class=\"modal fade\" role=\"dialog\">\n<div class=\"modal-dialog\">\n<div class=\"modal-content\">\n<div class=\"modal-body\">\n<p><strong>Estimado usu\u00e1rio.<\/strong><br \/>Preencha o formul\u00e1rio abaixo para remeter a p\u00e1gina.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row justify-content-md-center mt-3\">\n<div class=\"col-lg-auto col-image block-news-main-image\">\n<p>                                <br \/>\n                                                <span class=\"publicity-photo d-block mt-1\">Foto: Pixabay<\/span><\/p><\/div>\n<\/p><\/div>\n<div class=\"section-description section-description-noticias mt-3\">\n<p style=\"text-align:justify\">Segundo an\u00e1lise semanal do Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea) divulgada nesta segunda-feira (12), o esmagamento de soja em Mato Grosso atingiu 1,18 milh\u00e3o de toneladas em julho de 2025, estabelecendo novo recorde para o m\u00eas. O volume representa alta de 3,61% em rela\u00e7\u00e3o a junho e de 12,70% frente ao mesmo per\u00edodo de 2024.&#13;\n<\/p>\n<p style=\"text-align:justify\">O Imea informou que o aumento est\u00e1 relacionado \u00e0 maior demanda por \u00f3leo de soja no estado e \u00e0 retomada das ind\u00fastrias esmagadoras ap\u00f3s pausas programadas para manuten\u00e7\u00e3o no m\u00eas anterior. No acumulado do ano, entre janeiro e julho, o processamento alcan\u00e7ou 7,90 milh\u00f5es de toneladas, avan\u00e7o de 3,77% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado.&#13;\n<\/p>\n<p style=\"text-align:justify\">A proje\u00e7\u00e3o do instituto indica que, em 2025, o total de soja processada em Mato Grosso deve chegar a 12,99 milh\u00f5es de toneladas. \u201cCaso se confirme, ser\u00e1 um novo recorde para o processamento no estado\u201d, destacou o Imea.<\/p>\n<p style=\"text-align:justify\">Apesar do volume recorde, a margem bruta de esmagamento apresentou queda de 14,93% frente ao m\u00eas anterior, encerrando julho com m\u00e9dia mensal de R$ 433,78 por tonelada. Segundo o Imea, a retra\u00e7\u00e3o foi influenciada pela redu\u00e7\u00e3o nas cota\u00e7\u00f5es do farelo de soja e pelo aumento no pre\u00e7o da soja em Mato Grosso.&#13;\n<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><script data-cfasync=\"false\">\n    !function (f, b, e, v, n, t, s) {\n        if (f.fbq) return; n = f.fbq = function () {\n            n.callMethod ?\n                n.callMethod.apply(n, arguments) : n.queue.push(arguments)\n        };\n        if (!f._fbq) f._fbq = n; n.push = n; n.loaded = !0; n.version = '2.0';\n        n.queue = []; t = b.createElement(e); t.async = !0;\n        t.src = v; s = b.getElementsByTagName(e)[0];\n        s.parentNode.insertBefore(t, s)\n    }(window, document, 'script',\n        'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n    fbq('init', '522546078623747');\n    fbq('track', 'PageView');\n<\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.agrolink.com.br\/noticias\/mato-grosso--esmagamento-de-soja-bate-recorde-em-julho_504859.html\">AGROLINK<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; Demanda por \u00f3leo eleva esmagamento de soja&#13; &#13; Agrolink&#13; &#13; &#8211; Seane Lennon&#13; &#13; Publicado em 12\/08\/2025 \u00e0s 16:41h. Estimado usu\u00e1rio.Preencha o formul\u00e1rio abaixo para remeter a p\u00e1gina. Foto: Pixabay Segundo an\u00e1lise semanal do Instituto Mato-grossense de Economia Agropecu\u00e1ria (Imea) divulgada nesta segunda-feira (12), o esmagamento de soja em Mato Grosso atingiu 1,18 milh\u00e3o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":32498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[53],"tags":[],"class_list":["post-36660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/36660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=36660"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/36660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/32498"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=36660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=36660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=36660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}