{"id":32735,"date":"2025-07-27T08:40:59","date_gmt":"2025-07-27T11:40:59","guid":{"rendered":"https:\/\/mussicom.com\/antes-restrita-a-amazonia-febre-oropouche-se-espalha-pelo-pais\/"},"modified":"2025-07-27T08:40:59","modified_gmt":"2025-07-27T11:40:59","slug":"antes-restrita-a-amazonia-febre-oropouche-se-espalha-pelo-pais","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/antes-restrita-a-amazonia-febre-oropouche-se-espalha-pelo-pais\/","title":{"rendered":"Antes restrita \u00e0 Amaz\u00f4nia, febre oropouche se espalha pelo pa\u00eds"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>At\u00e9 2023, a febre oropouche era uma doen\u00e7a quase exclusiva dos estados da Regi\u00e3o Amaz\u00f4nica, mas este ano, o Esp\u00edrito Santo, a quase 3 mil km de dist\u00e2ncia se tornou recordista de casos com 6.318 registros.<\/strong> Pesquisadores tentam entender o que levou a doen\u00e7a a se espalhar pelo Brasil, e gestores de sa\u00fade pensam estrat\u00e9gias para controlar a oropouche em meio a uma popula\u00e7\u00e3o sem nenhuma imunidade pr\u00e9via.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1651702&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p><strong>Este ano, infec\u00e7\u00f5es por oropouche j\u00e1 foram confirmadas em 18 estados mais o Distrito Federal, somando 11.805 casos<\/strong>. Cinco pessoas morreram pela doen\u00e7a, 4 no Rio de Janeiro e 1 no Esp\u00edrito Santo e h\u00e1 duas mortes sendo investigadas. Em praticamente todas as semanas, os casos deste ano superam os do ano passado, e a <strong>expectativa \u00e9 que que a soma de 2025 seja superior a quantia de 13.856 registrada em 2024. O n\u00famero de mortos j\u00e1 \u00e9 superior. No ano passado, foram quatro: 2 na Bahia, 1 no Esp\u00edrito Santo e 1 em Santa Catarina.<\/strong><\/p>\n<p>A febre oropouche \u00e9 causada por um v\u00edrus transmitido pelo mosquito Culicoides paraensis, mais conhecido como maruim ou mosquito-p\u00f3lvora, incidente em todo o pa\u00eds. <strong>Ela causa sintomas semelhantes aos de outras doen\u00e7as transmitidas por mosquitos, como dengue e chikungunya, principalmente febre e dor na cabe\u00e7a, m\u00fasculos e articula\u00e7\u00f5es.<\/strong><\/p>\n<p>A <strong>infec\u00e7\u00e3o tamb\u00e9m pode causar complica\u00e7\u00f5es na gravidez, incluindo microcefalia, malforma\u00e7\u00f5es e \u00f3bito do feto, assim como o Zika virus.<\/strong> Por isso, o <strong>Minist\u00e9rio da Sa\u00fade recomenda que as gestantes que vivem em \u00e1reas com registros da doen\u00e7a reforcem a prote\u00e7\u00e3o contra os mosquitos.<\/strong> Apesar da transmiss\u00e3o do v\u00edrus por via sexual ainda n\u00e3o ter sido comprovada, pessoas com sintomas tamb\u00e9m devem usar preservativo durante as rela\u00e7\u00f5es sexuais como medida preventiva.<\/p>\n<p>De acordo com o chefe do Laborat\u00f3rio de Arbov\u00edrus e Hemorr\u00e1gicos do Instituto Oswaldo Cruz, Felipe Naveca, <strong>estudos gen\u00e9ticos mostram que os casos que se proliferam no Brasil foram causados por uma nova linhagem do v\u00edrus, que surgiu no Amazonas, circulou pela Regi\u00e3o Norte e depois se espalhou.<\/strong><\/p>\n<blockquote>\n<p>&#8220;E n\u00f3s tamb\u00e9m conseguimos mostrar que esse cen\u00e1rio est\u00e1 muito relacionado com algumas \u00e1reas de desmatamento recente, principalmente no sul do Amazonas e no norte de Rond\u00f4nia, que serviram como pontos cruciais para dispers\u00e3o desse v\u00edrus. A\u00ed pessoas infectadas acabaram levando para fora da Regi\u00e3o, porque depois que ela \u00e9 infectada pelo v\u00edrus, leva um tempo at\u00e9 manifestar os sintomas&#8221;, complementa Naveca.<\/p>\n<\/blockquote>\n<p>O maruim existe em todo pa\u00eds, mas precisa de ambientes \u00famidos e com mat\u00e9ria org\u00e2nica em decomposi\u00e7\u00e3o para se reproduzir, por isso, \u00e9 mais incidente em \u00e1reas florestais e de planta\u00e7\u00f5es, especialmente nas lavouras de banana. Os <strong>surtos t\u00eam ocorrido principalmente em regi\u00f5es periurbanas, de transi\u00e7\u00e3o entre ambientes rurais e de mata e \u00e1reas habitadas por humanos. Apenas as f\u00eameas transmitem o v\u00edrus da febre oropouche, que tamb\u00e9m podem ser inoculados em animais.<\/strong><\/p>\n<blockquote>\n<p>Segundo Naveca, as mudan\u00e7as ambientais tamb\u00e9m t\u00eam um papel na prolifera\u00e7\u00e3o da doen\u00e7a. &#8220;Todas as vezes que voc\u00ea tem eventos mais extremos, seja de seca ou cheia dos rios, isso afeta a popula\u00e7\u00e3o n\u00e3o s\u00f3 do vetor, mas tamb\u00e9m dos animais que o mosquito se alimenta. Ent\u00e3o, isso modifica todo esse ecossistema. Os nossos dados mostram que a popula\u00e7\u00e3o do v\u00edrus, aumentava justamente nos per\u00edodos de chuva na Regi\u00e3o Amaz\u00f4nica.&#8221;<\/p>\n<\/blockquote>\n<p>Um estudo internacional recente analisou dados de seis pa\u00edses sulamericanos, incluindo o Brasil, e identificou que\u00a0as vari\u00e1veis clim\u00e1ticas, como as\u00a0mudan\u00e7as\u00a0de padr\u00e3o da\u00a0temperatura e da\u00a0chuva, foram os principais fatores de influ\u00eancia para a dissemina\u00e7\u00e3o da oropouche, contribuindo com 60%. Por isso, os <strong>pesquisadores acreditam que eventos clim\u00e1ticos extremos, como o\u00a0El Ni\u00f1o, provavelmente tiveram um papel fundamental no surto iniciado em 2023.<\/strong><\/p>\n<p>O Minist\u00e9rio da Sa\u00fade refor\u00e7ou o monitoramento dos casos de Oropouche e tem feito reuni\u00f5es peri\u00f3dicas e visitas t\u00e9cnicas aos estados, para orientar as autoridades locais sobre as formas corretas de notificar, investigar e encerrar os casos suspeitos.<\/p>\n<blockquote>\n<p>&#8220;Em parceria com a Fiocruz e a Embrapa, a pasta realiza estudos sobre o uso de inseticidas para o controle do vetor, com resultados preliminares promissores. As evid\u00eancias apoiam a defini\u00e7\u00e3o de estrat\u00e9gias de enfrentamento da doen\u00e7a, especialmente durante surtos, e a redu\u00e7\u00e3o de seu impacto na popula\u00e7\u00e3o. A preven\u00e7\u00e3o inclui o uso de roupas compridas, sapatos fechados, telas de malha fina nas janelas e elimina\u00e7\u00e3o de mat\u00e9ria org\u00e2nica acumulada&#8221;, declarou o Minist\u00e9rio em nota.<\/p>\n<\/blockquote>\n<h2>Esp\u00edrito Santo<\/h2>\n<p>As <strong>autoridades de sa\u00fade do Esp\u00edrito Santo tamb\u00e9m est\u00e3o em alerta j\u00e1 que o pequeno estado com pouco mais de 4 milh\u00f5es de habitantes se tornou o recordista de casos no ano passado e este ano.<\/strong> O subsecret\u00e1rio estadual de Vigil\u00e2ncia em Sa\u00fade, Orlei Cardoso, explica que boa parte dos 78 munic\u00edpios capixabas t\u00eam caracter\u00edsticas periurbanas, com muitas \u00e1reas de planta\u00e7\u00e3o, o que facilita a reprodu\u00e7\u00e3o do maruim. Com mosquitos em abund\u00e2ncia, e uma popula\u00e7\u00e3o sem imunidade pr\u00e9via, o v\u00edrus encontrou as condi\u00e7\u00f5es ideais para se disseminar.<\/p>\n<blockquote>\n<p>&#8220;N\u00f3s identificamos tamb\u00e9m que os primeiros casos ocorreram na \u00e9poca da colheita do caf\u00e9, que \u00e9 um per\u00edodo que circulam muitas pessoas que v\u00eam de outros estados para trabalhar nas lavouras. Isso acaba sendo um momento favor\u00e1vel para a transmiss\u00e3o, ainda porque os trabalhadores passam uma semana em uma cidade, depois seguem para outra&#8230;&#8221; complementa Cardoso.<\/p>\n<\/blockquote>\n<p><strong>Enquanto os pesquisadores trabalham para mapear as \u00e1reas de maior incid\u00eancia do maruim, a secretaria refor\u00e7a o treinamento dos profissionais de sa\u00fade.<\/strong><\/p>\n<blockquote>\n<p>&#8220;Como era uma doen\u00e7a desconhecida, eles come\u00e7aram a entender agora o que est\u00e1 acontecendo, para saber identificar e agir diante de um caso de Oropouche. Ent\u00e3o n\u00f3s estamos fazendo a qualifica\u00e7\u00e3o das equipes municipais, para fazer o reconhecimento cl\u00ednico, principalmente diferenciar a oropouche da dengue e das outras arboviroses e estamos treinando tamb\u00e9m os agentes comunit\u00e1rios de sa\u00fade&#8221;, garante o subsecret\u00e1rio estadual de Vigil\u00e2ncia em Sa\u00fade.<\/p>\n<\/blockquote>\n<p>A <strong>febre oropouche tamb\u00e9m se tornou uma novidade indesej\u00e1vel em alguns estados da Regi\u00e3o Nordeste, com destaque para o Cear\u00e1, que registrou 674 casos este ano.<\/strong> De acordo com o Secret\u00e1rio Executivo de Vigil\u00e2ncia em Sa\u00fade do estado, Antonio Lima\u00a0Neto, os casos no Cear\u00e1 tamb\u00e9m come\u00e7aram em \u00e1reas de plantio, principalmente de banana, mas tamb\u00e9m de cacau e mandioca.<\/p>\n<blockquote>\n<p>&#8220;No primeiro ano, n\u00f3s tivemos 255 casos, que se concentraram em distritos rurais, com pequenos povoados, todos localizados na regi\u00e3o Serrana do Cear\u00e1, conhecida como Maci\u00e7o de Baturit\u00e9. Em 2025, quando a doen\u00e7a retornou, ocorreu algo diferente que foi uma transi\u00e7\u00e3o da doen\u00e7a para a principal cidade da regi\u00e3o, que \u00e9 Baturit\u00e9. Onde, ao inv\u00e9s de voc\u00ea ter 500 moradores, voc\u00ea tem 20.000 pessoas&#8221;, complementa.<\/p>\n<\/blockquote>\n<p><strong>De acordo com o secret\u00e1rio executivo, o estado tamb\u00e9m est\u00e1 investindo em a\u00e7\u00f5es de manejo cl\u00ednico e vigil\u00e2ncia laboratorial, para diagnosticar corretamente a doen\u00e7a, especialmente em gestantes. O Cear\u00e1 foi um dos estados que registrou a morte de um feto, ap\u00f3s a infec\u00e7\u00e3o da m\u00e3e por oropouche. No ano passado, pelo menos cinco casos de \u00f3bito fetal e um caso de anomalia cong\u00eanita foram registrados no Brasil, causados pelo v\u00edrus.<\/strong><\/p>\n<blockquote>\n<p>&#8220;O controle vetorial de um mosquito domiciliado, ele tem um fundamento central, que \u00e9 a elimina\u00e7\u00e3o de criadores, como no caso do <em>Aedes Aegypt<\/em>. Voc\u00ea eliminar os locais onde ele se reproduz, voc\u00ea renovar a \u00e1gua, cuidar do lixo dom\u00e9stico&#8230; Com o mosquito-p\u00f3lvora, voc\u00ea teria que fazer uma barreira qu\u00edmica entre as planta\u00e7\u00f5es e as \u00e1reas onde as pessoas vivem,. O Minist\u00e9rio da Sa\u00fade tem realizados testes em busca de produtos eficientes, mas n\u00e3o \u00e9 algo trivial&#8221;, afirma Antonio Lima\u00a0Neto.<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2025-07\/antes-restrita-amazonia-febre-oropouche-se-espalha-pelo-pais\">Ag\u00eancia Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 2023, a febre oropouche era uma doen\u00e7a quase exclusiva dos estados da Regi\u00e3o Amaz\u00f4nica, mas este ano, o Esp\u00edrito Santo, a quase 3 mil km de dist\u00e2ncia se tornou recordista de casos com 6.318 registros. Pesquisadores tentam entender o que levou a doen\u00e7a a se espalhar pelo Brasil, e gestores de sa\u00fade pensam estrat\u00e9gias [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":32736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-32735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/32735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=32735"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/32735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/32736"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=32735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=32735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=32735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}