{"id":30335,"date":"2025-07-18T16:32:20","date_gmt":"2025-07-18T19:32:20","guid":{"rendered":"https:\/\/mussicom.com\/mais-de-196-milhoes-de-familias-recebem-o-bolsa-familia-a-partir-desta-sexta-18\/"},"modified":"2025-07-18T16:32:20","modified_gmt":"2025-07-18T19:32:20","slug":"mais-de-196-milhoes-de-familias-recebem-o-bolsa-familia-a-partir-desta-sexta-18","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/mais-de-196-milhoes-de-familias-recebem-o-bolsa-familia-a-partir-desta-sexta-18\/","title":{"rendered":"Mais de 19,6 milh\u00f5es de fam\u00edlias recebem o Bolsa Fam\u00edlia a partir desta sexta, 18"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>\n\t\t\t\t\t\tCalend\u00e1rio de repasses do Bolsa Fam\u00edlia em julho segue at\u00e9 o dia 31<br \/>\n\t\t\t\t\t\t &#8211; \t\t\t\t\t\tRoberta Aline \/ MDS\n\t\t\t\t\t<\/p>\n<div id=\"texto\">\n<p>O cronograma de pagamentos do Bolsa Fam\u00edlia em julho tem in\u00edcio nesta sexta-feira, dia 18. Neste m\u00eas, mais de 19,6 milh\u00f5es de fam\u00edlias, de todos os 5.570 munic\u00edpios brasileiros, recebem o benef\u00edcio, em um investimento de R$ 13,1 bilh\u00f5es por parte do Governo Federal. O valor m\u00e9dio \u00e9 de R$ 671,52. O calend\u00e1rio de repasses (<strong>infogr\u00e1fico abaixo<\/strong>) do programa de transfer\u00eancia de renda leva em considera\u00e7\u00e3o o final do N\u00famero de Identifica\u00e7\u00e3o Social (NIS) e segue at\u00e9 o dia 31.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>ADICIONAIS<\/strong>\u00a0\u2014 Mais de 8,5 milh\u00f5es de crian\u00e7as de zero a seis anos recebem o Benef\u00edcio Primeira Inf\u00e2ncia neste m\u00eas. O adicional de R$ 150 \u00e9 repassado a cada integrante do n\u00facleo familiar dos benefici\u00e1rios nessa faixa et\u00e1ria, a partir de um investimento de R$ 1,2 bilh\u00e3o. Outros tr\u00eas benef\u00edcios, todos de R$ 50 adicionais, chegam a 648 mil gestantes, 273 mil nutrizes (em fase de amamenta\u00e7\u00e3o) e 14,6 milh\u00f5es de crian\u00e7as e adolescentes entre sete e 18 anos. O valor somado para saldar esses benef\u00edcios \u00e9 de R$ 714 milh\u00f5es.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p>\u00bb Confira os recortes estaduais do Bolsa Fam\u00edlia em julho de 2025<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>VULNER\u00c1VEIS<\/strong>\u00a0\u2014 Em julho, o Bolsa Fam\u00edlia beneficia, em seu grupo priorit\u00e1rio, 243 mil fam\u00edlias ind\u00edgenas, 282 mil fam\u00edlias quilombolas, 261 mil fam\u00edlias com pessoas em situa\u00e7\u00e3o de rua e 382 mil fam\u00edlias de catadores de material recicl\u00e1vel.<\/p>\n<p>\u00a0<\/p>\n<table align=\"center\" style=\"width:1080px\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td>&#13;<\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:1080px\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td width=\"1080\">Calend\u00e1rio de pagamento do Bolsa Fam\u00edlia em julho de 2025<\/td>\n<p>&#13;<br \/>\n\t\t\t\t\t<\/tr>\n<p>&#13;<br \/>\n\t\t\t\t<\/tbody>\n<p>&#13;<br \/>\n\t\t\t<\/table>\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<br \/>\n\t<\/tbody>\n<p>&#13;<br \/>\n<\/table>\n<p>\u00a0<\/p>\n<p><strong>PERFIL<\/strong>\u00a0\u2014 Como costuma ocorrer no programa de transfer\u00eancia de renda do Governo Federal, 83,9% dos respons\u00e1veis familiares s\u00e3o mulheres: 16,4 milh\u00f5es. Do total de pessoas que recebem os benef\u00edcios em julho, 29,9 milh\u00f5es s\u00e3o do sexo feminino (58,5%). As pessoas de cor preta\/parda representam a predomin\u00e2ncia entre os benefici\u00e1rios e somam 37,4 milh\u00f5es (73,1%).<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>REGRA DE PROTE\u00c7\u00c3O<\/strong>\u00a0\u2014 A Regra de Prote\u00e7\u00e3o permite aos benefici\u00e1rios permanecerem no programa mesmo depois de conseguirem emprego com carteira assinada ou aumento de renda. Nesse caso, a fam\u00edlia recebe 50% do valor. Esse par\u00e2metro atinge, em julho, 2,6 milh\u00f5es de fam\u00edlias.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>QUASE UM MILH\u00c3O SAEM DA POBREZA<\/strong>\u00a0&#8211; Em julho, o Bolsa Fam\u00edlia tem tamb\u00e9m um marco importante.\u00a0Quase um milh\u00e3o de fam\u00edlias (958 mil) deixam o programa porque obtiveram aumento da renda familiar, seja por terem conquistado emprego ou por se tornarem empreendedores. S\u00e3o 536 mil que encerram o prazo de dois anos na Regra de Prote\u00e7\u00e3o, per\u00edodo em que recebem metade do valor, e 421 mil fam\u00edlias que atingiram renda familiar acima do limite previsto entre os requisitos, de meio sal\u00e1rio m\u00ednimo por integrante do n\u00facleo familiar. Em todo o Brasil, s\u00e3o 958 mil fam\u00edlias que saem do Bolsa Fam\u00edlia neste m\u00eas por superarem a fronteira da pobreza.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p>&#8220;S\u00e3o quase um milh\u00e3o de fam\u00edlias superando a pobreza neste m\u00eas no Brasil. Isso \u00e9 fruto de um trabalho de qualifica\u00e7\u00e3o profissional, de apoio ao empreendedorismo, garantindo que as pessoas tenham condi\u00e7\u00e3o de elevar a renda&#8221;, afirmou o ministro Wellington Dias (Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome). &#8220;A pessoa sai do Bolsa Fam\u00edlia, mas n\u00e3o do Cadastro \u00danico. Se l\u00e1 na frente perder o emprego, a renda, volta automaticamente para a prote\u00e7\u00e3o social, para o Bolsa Fam\u00edlia. Mas s\u00e3o quase um milh\u00e3o de fam\u00edlias do Brasil que agora t\u00eam mais dignidade. Isso mostra que o povo do Bolsa Fam\u00edlia quer trabalhar, quer emprego decente, quer ajudar o Brasil a crescer&#8221;, completou.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>UNIFICADO<\/strong>\u00a0\u2014 Em 516 munic\u00edpios de seis estados, o pagamento do Bolsa Fam\u00edlia em julho ser\u00e1 feito integralmente nesta sexta-feira, 18 de julho, primeiro dia do cronograma. S\u00e3o cidades e regi\u00f5es inclu\u00eddas nas a\u00e7\u00f5es de enfrentamento a desastres, como enchentes, inunda\u00e7\u00f5es e per\u00edodos longos de seca e estiagem. A iniciativa beneficia diretamente 703 mil fam\u00edlias. Na lista est\u00e3o todos os 497 munic\u00edpios do Rio Grande do Sul, al\u00e9m de Alagoas (seis munic\u00edpios), Roraima (6), Amazonas (3), Paran\u00e1 (3) e S\u00e3o Paulo (1).<br \/>&#13;<br \/>\n\u00a0<\/p>\n<table align=\"center\" style=\"width:904px\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td><img decoding=\"async\" src=\"https:\/\/s2506.imxsnd102.com\/84ImO3YDN5EWY6InYu02bj5SOzJGQv12cpxWYuJ3bqpTNzYTNyYzM2kzM6cGcq5yM2kzN1gDO1gjRyUCO1gzb0VXYGJTJ2IDMx8VL1ETLf9VLwITLfpDN\" style=\"width:904px\"\/>&#13;<\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:904px\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td width=\"904\">Principais dados do Bolsa Fam\u00edlia em julho de 2025<\/td>\n<p>&#13;<br \/>\n\t\t\t\t\t<\/tr>\n<p>&#13;<br \/>\n\t\t\t\t<\/tbody>\n<p>&#13;<br \/>\n\t\t\t<\/table>\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<br \/>\n\t<\/tbody>\n<p>&#13;<br \/>\n<\/table>\n<p>\u00a0<\/p>\n<p><strong>REGI\u00d5ES\u00a0<\/strong>\u2014 No recorte por regi\u00f5es, a Nordeste re\u00fane o maior n\u00famero de contemplados em julho. S\u00e3o 9 milh\u00f5es de benefici\u00e1rios, a partir de um investimento de R$ 6 bilh\u00f5es. Na sequ\u00eancia aparece a regi\u00e3o Sudeste (5,6 milh\u00f5es de fam\u00edlias e R$ 3,6 bilh\u00f5es em repasses), seguida por Norte (2,5 milh\u00f5es de fam\u00edlias e R$ 1,8 bilh\u00e3o), Sul (1,3 milh\u00e3o de benefici\u00e1rios e R$ 895 milh\u00f5es) e Centro-Oeste (1 milh\u00e3o de fam\u00edlias e R$ 700 milh\u00f5es).<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>ESTADOS<\/strong>\u00a0\u2014 Na divis\u00e3o por unidades federativas, o maior n\u00famero de contemplados em julho est\u00e1 na Bahia. S\u00e3o 2,38 milh\u00f5es de fam\u00edlias benefici\u00e1rias no estado, a partir de um aporte federal de R$ 1,57 bilh\u00e3o. S\u00e3o Paulo aparece na sequ\u00eancia, com 2, 3 milh\u00f5es de contemplados. Em outros seis h\u00e1 mais de um milh\u00e3o de integrantes do programa: Pernambuco (1,52 milh\u00e3o), Rio de Janeiro (1,51 milh\u00e3o), Minas Gerais (1,48 milh\u00e3o), Cear\u00e1 (1,4 milh\u00e3o), Par\u00e1 (1,3 milh\u00e3o) e Maranh\u00e3o (1,19 milh\u00e3o).<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p><strong>VALOR M\u00c9DIO<\/strong>\u00a0\u2014 Roraima \u00e9 o estado com maior valor m\u00e9dio de repasse para os benefici\u00e1rios em julho: R$ 736,67. O Amazonas, com R$ 725,73, e o Acre, com R$ 720,85, completam a lista das tr\u00eas maiores m\u00e9dias nos estados. Quando o recorte leva em conta os 5.570 munic\u00edpios brasileiros, o maior valor m\u00e9dio est\u00e1 em Uiramut\u00e3, munic\u00edpio de 13,7 mil habitantes em Roraima, com 2.2 mil fam\u00edlias atendidas pelo programa neste m\u00eas e t\u00edquete m\u00e9dio de R$ 1.018. Na sequ\u00eancia aparecem os munic\u00edpios de Campin\u00e1polis (MT), com R$ 917; Santa Rosa do Purus (AC), com R$ 897; e Jord\u00e3o (AC), com R$ 874.<\/p>\n<p>\u00a0<\/p>\n<p><em><strong>Fonte:<\/strong>\u00a0Secretaria de Comunica\u00e7\u00e3o Social da Presid\u00eancia da Rep\u00fablica<\/em><\/p>\n<\/p><\/div>\n<p><script async defer crossorigin=\"anonymous\" src=\"https:\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&#038;version=v12.0&#038;appId=&#038;autoLogAppEvents=1\" nonce=\"ou0fI1lo\"><\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.bs9.com.br\/brasil\/mais-de-196-milhoes-de-familias-recebem-o-bolsa-familia-a-partir\/33340\/\">BS9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calend\u00e1rio de repasses do Bolsa Fam\u00edlia em julho segue at\u00e9 o dia 31 &#8211; Roberta Aline \/ MDS O cronograma de pagamentos do Bolsa Fam\u00edlia em julho tem in\u00edcio nesta sexta-feira, dia 18. Neste m\u00eas, mais de 19,6 milh\u00f5es de fam\u00edlias, de todos os 5.570 munic\u00edpios brasileiros, recebem o benef\u00edcio, em um investimento de R$ [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":30336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[52],"tags":[],"class_list":["post-30335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santoseregiao"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/30335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=30335"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/30335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/30336"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=30335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=30335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=30335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}