{"id":26338,"date":"2025-06-13T18:39:58","date_gmt":"2025-06-13T21:39:58","guid":{"rendered":"https:\/\/mussicom.com\/em-guaruja-projeto-negocio-de-mae-transforma-espera-em-empreendedorismo\/"},"modified":"2025-06-13T18:39:58","modified_gmt":"2025-06-13T21:39:58","slug":"em-guaruja-projeto-negocio-de-mae-transforma-espera-em-empreendedorismo","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/em-guaruja-projeto-negocio-de-mae-transforma-espera-em-empreendedorismo\/","title":{"rendered":"Em Guaruj\u00e1, projeto &#8220;Neg\u00f3cio de M\u00e3e&#8221; transforma espera em empreendedorismo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"texto\">\n<p>Com objetivo de oferecer acolhimento e oportunidades para m\u00e3es at\u00edpicas, o projeto &#8220;Neg\u00f3cio de M\u00e3e&#8221; foi lan\u00e7ado marcando o in\u00edcio de um ciclo de encontros voltados para o empoderamento dessas mulheres. Idealizado pelo Fundo Social de Solidariedade (FSS) de Guaruj\u00e1, em parceria com Associa\u00e7\u00e3o de Pais e Amigos dos Autistas de Guaruj\u00e1 (APAAG), o projeto conta com o apoio do Espa\u00e7o Empreenda Mais.<\/p>\n<p>\u00a0<\/p>\n<p>O encontro inicial ocorreu na sede da APAAG e reuniu 25 m\u00e3es at\u00edpicas, que acompanham seus filhos durante atendimentos terap\u00eauticos. A iniciativa visa transformar o tempo de espera dessas mulheres em oportunidades de acolhimento, capacita\u00e7\u00e3o e orienta\u00e7\u00e3o empreendedora. O objetivo principal \u00e9 promover independ\u00eancia financeira e fortalecer o papel dessas m\u00e3es em suas comunidades.<\/p>\n<p>\u00a0<\/p>\n<p>Al\u00e9m de oferecer capacita\u00e7\u00e3o t\u00e9cnica, o projeto proporciona um espa\u00e7o de escuta e valoriza\u00e7\u00e3o das participantes, reconhecendo os desafios \u00fanicos enfrentados na maternidade at\u00edpica e incentivando novos caminhos por meio do empreendedorismo. Os encontros continuar\u00e3o ao longo dos pr\u00f3ximos meses, com a proposta de fortalecer a rede de apoio \u00e0s m\u00e3es at\u00edpicas e ampliar o impacto do projeto.<\/p>\n<p>\u00a0<\/p>\n<p>A primeira-dama e presidente do Fundo Social de Solidariedade de Guaruj\u00e1, Haifa Madi, participou da abertura e destacou o compromisso da Administra\u00e7\u00e3o Municipal em criar a\u00e7\u00f5es que integrem acolhimento, capacita\u00e7\u00e3o e gera\u00e7\u00e3o de renda para fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade social. &#8220;A iniciativa busca valorizar o potencial de cada participante, promovendo transforma\u00e7\u00f5es significativas em suas vidas e no contexto familiar&#8221;, afirmou Haifa.<\/p>\n<\/p><\/div>\n<p><script async defer crossorigin=\"anonymous\" src=\"https:\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&#038;version=v12.0&#038;appId=&#038;autoLogAppEvents=1\" nonce=\"ou0fI1lo\"><\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.bs9.com.br\/litoral\/em-guaruja-projeto-negocio-de-mae-transforma-espera-em\/32513\/\">BS9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com objetivo de oferecer acolhimento e oportunidades para m\u00e3es at\u00edpicas, o projeto &#8220;Neg\u00f3cio de M\u00e3e&#8221; foi lan\u00e7ado marcando o in\u00edcio de um ciclo de encontros voltados para o empoderamento dessas mulheres. Idealizado pelo Fundo Social de Solidariedade (FSS) de Guaruj\u00e1, em parceria com Associa\u00e7\u00e3o de Pais e Amigos dos Autistas de Guaruj\u00e1 (APAAG), o projeto [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[52],"tags":[],"class_list":["post-26338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santoseregiao"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/26338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=26338"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/26338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/26339"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=26338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=26338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=26338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}