{"id":23958,"date":"2025-05-29T21:41:32","date_gmt":"2025-05-30T00:41:32","guid":{"rendered":"https:\/\/mussicom.com\/deputada-dos-eua-cita-moraes-em-post-sobre-restricao-de-vistos\/"},"modified":"2025-05-29T21:41:32","modified_gmt":"2025-05-30T00:41:32","slug":"deputada-dos-eua-cita-moraes-em-post-sobre-restricao-de-vistos","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/deputada-dos-eua-cita-moraes-em-post-sobre-restricao-de-vistos\/","title":{"rendered":"Deputada dos EUA cita Moraes em post sobre restri\u00e7\u00e3o de vistos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"postParagraph_post-paragraph__juWZN\">A deputada republicana da Fl\u00f3rida Maria Elvira Salazar manifestou nesta quarta-feira (28) apoio \u00e0 nova pol\u00edtica dos Estados Unidos de restri\u00e7\u00e3o de vistos para autoridades estrangeiras acusadas de censurar americanos, citando nominalmente o ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF).<\/p>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">No post divulgado em suas redes sociais, Salazar afirmou que apoia &#8220;totalmente a decis\u00e3o do secret\u00e1rio Rubio de negar vistos americanos a autoridades estrangeiras que silenciam americanos no exterior. Que isso sirva de alerta para tiranos ao redor do mundo e simpatizantes autorit\u00e1rios como Alexandre de Moraes, do Brasil: se tentarem censurar cidad\u00e3os americanos, mesmo al\u00e9m das nossas fronteiras, n\u00e3o ser\u00e3o bem-vindos nos Estados Unidos. Os dias em que repressores desfrutavam das nossas liberdades enquanto as negavam a outros acabaram. A liberdade de express\u00e3o \u00e9 sagrada, e vamos defend\u00ea-la em todo lugar\u201d.<\/p>\n<div class=\"postImage_post-content-image__2CJdu\"><picture class=\"imageDefault_image-container__XGd8_\"><\/picture><\/div>\n<p class=\"postParagraph_post-paragraph__juWZN\">Salazar escreveu tal texto ao compartilhar a publica\u00e7\u00e3o do secret\u00e1rio de Estado americano, Marco Rubio, anunciando a medida. Em sua publica\u00e7\u00e3o, Rubio disse que \u201cpor muito tempo, os americanos foram multados, assediados e at\u00e9 mesmo acusados por autoridades estrangeiras por exercerem seus direitos de liberdade de express\u00e3o&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/mundo\/deputada-republicana-cita-moraes-e-lanca-aviso-censores-nao-sao-bem-vindos-nos-estados-unidos\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A deputada republicana da Fl\u00f3rida Maria Elvira Salazar manifestou nesta quarta-feira (28) apoio \u00e0 nova pol\u00edtica dos Estados Unidos de restri\u00e7\u00e3o de vistos para autoridades estrangeiras acusadas de censurar americanos, citando nominalmente o ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF). No post divulgado em suas redes sociais, Salazar afirmou que apoia &#8220;totalmente a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":23959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-23958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/23958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=23958"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/23958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/23959"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=23958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=23958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=23958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}