{"id":20717,"date":"2025-05-15T22:09:41","date_gmt":"2025-05-16T01:09:41","guid":{"rendered":"https:\/\/mussicom.com\/ednaldo-rodrigues-e-afastado-da-presidencia-da-cbf\/"},"modified":"2025-05-15T22:09:41","modified_gmt":"2025-05-16T01:09:41","slug":"ednaldo-rodrigues-e-afastado-da-presidencia-da-cbf","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/ednaldo-rodrigues-e-afastado-da-presidencia-da-cbf\/","title":{"rendered":"Ednaldo Rodrigues \u00e9 afastado da presid\u00eancia da CBF"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A diretoria da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), incluindo o presidente Ednaldo Rodrigues, foi afastada do comando da entidade no final da tarde desta quinta-feira (15), seguindo determina\u00e7\u00e3o do desembargador do Tribunal de Justi\u00e7a do Rio de Janeiro Gabriel de Oliveira Zefiro.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1642884&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p>A decis\u00e3o tamb\u00e9m determina que Fernando Sarney, um dos vice-presidente da CBF e que pediu \u00e0 Justi\u00e7a o afastamento de Rodrigues, atue como interventor da entidade, tendo como uma de suas principais responsabilidades realizar elei\u00e7\u00f5es \u201co mais r\u00e1pido poss\u00edvel\u201d.<\/p>\n<p>O afastamento de Ednaldo Rodrigues da presid\u00eancia da CBF acontece dez dias ap\u00f3s a deputada federal\u00a0Daniela Carneiro (Uni\u00e3o Brasil\/RJ), mais conhecida como Daniela do Waguinho, entrar com uma peti\u00e7\u00e3o no Supremo Tribunal Federal (STF) pedindo o afastamento imediato do dirigente. Al\u00e9m disso, a parlamentar solicitava a revis\u00e3o do acordo homologado pelo STF em fevereiro, que reconheceu a legalidade do processo eleitoral da entidade em 2022.<\/p>\n<p>A peti\u00e7\u00e3o protocolada pela deputada e ex-ministra do Turismo apontava, na ocasi\u00e3o, a\u00a0falsifica\u00e7\u00e3o de uma das cinco assinaturas que ratificaram o acordo homologado pelo STF no in\u00edcio do ano. Trata-se da assinatura de Ant\u00f4nio Carlos Nunes, tamb\u00e9m conhecido como Coronel Nunes, ex-presidente da CBF e um dos vice-presidentes da entidade no mandato anterior de Ednaldo Rodrigues.\u00a0A parlamentar questionava o acordo, com base no artigo 168 do C\u00f3digo Civil, que d\u00e1 permiss\u00e3o ao juiz de anular \u201cneg\u00f3cio jur\u00eddico ou seus efeitos\u201d quando houver v\u00edcio de consentimento.<\/p>\n<p>\u201cDeclaro nulo o acordo firmado entre as partes, homologado outrora pela Corte Superior, em raz\u00e3o da incapacidade mental e de poss\u00edvel falsifica\u00e7\u00e3o da assinatura de um dos signat\u00e1rios, Ant\u00f4nio Carlos Nunes de Lima, conhecido por Coronel Nunes\u201d, afirma o desembargador Gabriel de Oliveira Zefirona decis\u00e3o publicada nesta quinta.<\/p>\n<p>\u201cA consequ\u00eancia imediata e l\u00f3gica consiste no reconhecimento da ilegitimidade da atual administra\u00e7\u00e3o da CBF, fruto do acordo declarado nulo. A entidade n\u00e3o pode restar ac\u00e9fala e \u00e9 imperativo que se realizem elei\u00e7\u00f5es l\u00edcitas, dentro da legalidade estatut\u00e1ria\u201d, acrescenta a nota.<\/p>\n<p>Ednaldo Rodrigues, que est\u00e1 no Paraguai participando do congresso da Federa\u00e7\u00e3o Internacional de Futebol (FIFA), \u00e9 afastado do comando da CBF tr\u00eas dias ap\u00f3s anunciar a contrata\u00e7\u00e3o do t\u00e9cnico italiano Carlo Ancelotti, atualmente no Real Madrid (Espanha), para assumir o comando da sele\u00e7\u00e3o brasileira.<\/p>\n<p><em><strong>* Com informa\u00e7\u00f5es da ag\u00eancia de not\u00edcias Reuters.<\/strong><\/em><\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2025-05\/ednaldo-rodrigues-e-afastado-da-presidencia-da-cbf\">Ag\u00eancia Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diretoria da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), incluindo o presidente Ednaldo Rodrigues, foi afastada do comando da entidade no final da tarde desta quinta-feira (15), seguindo determina\u00e7\u00e3o do desembargador do Tribunal de Justi\u00e7a do Rio de Janeiro Gabriel de Oliveira Zefiro. A decis\u00e3o tamb\u00e9m determina que Fernando Sarney, um dos vice-presidente da CBF e [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[40],"tags":[],"class_list":["post-20717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=20717"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/20718"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=20717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=20717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=20717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}