{"id":20685,"date":"2025-05-15T19:58:47","date_gmt":"2025-05-15T22:58:47","guid":{"rendered":"https:\/\/mussicom.com\/gripe-e-a-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz\/"},"modified":"2025-05-15T19:58:47","modified_gmt":"2025-05-15T22:58:47","slug":"gripe-e-a-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/gripe-e-a-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz\/","title":{"rendered":"Gripe \u00e9 a principal causa de mortes por SRAG em idosos, alerta Fiocruz"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>O boletim InfoGripe, da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) divulgado nesta quinta-feira (15) faz uma alerta sobre o v\u00edrus da influenza A, causador da gripe, que se tornou a principal causa de mortalidade por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) em idosos e uma das tr\u00eas principais causas de \u00f3bitos entre as crian\u00e7as.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1642887&amp;o=node\" style=\"width:1px; height:1px; display:inline;\"\/><\/p>\n<p><strong>Foi registrado tamb\u00e9m um aumento nas hospitaliza\u00e7\u00f5es por influenza A em diversas partes do pa\u00eds<\/strong>, com n\u00edveis moderados a altos de incid\u00eancia em estados do Centro-Sul e nas regi\u00f5es do Norte e Nordeste.<\/p>\n<p>Em alguns estados das regi\u00f5es Centro-Oeste e Sudeste, o n\u00famero de casos de SRAG em crian\u00e7as pequenas, associado ao V\u00edrus Sincicial Respirat\u00f3rio (VSR) vem apresentando sinais de desacelera\u00e7\u00e3o ou at\u00e9 de revers\u00e3o.\u00a0<\/p>\n<blockquote>\n<p>\u201cApesar disso, ainda n\u00e3o \u00e9 o momento de relaxar os cuidados nessas regi\u00f5es, j\u00e1 que a incid\u00eancia de casos continua alta ou moderada\u201d, avalia a pesquisadora do InfoGripe Tatiana Portella.<\/p>\n<\/blockquote>\n<p>A especialista chama a aten\u00e7\u00e3o que a mortalidade por SRAG nas crian\u00e7as pequenas se aproxima da observada nos idosos. A principal causa de mortalidade por SRAG nos idosos \u00e9 o v\u00edrus da influenza A, seguida pela Covid-19. J\u00e1 nas crian\u00e7as, o VSR permanece como a principal causa de mortalidade por SRAG, seguido pelo rinov\u00edrus e pela influenza A.<\/p>\n<p><strong>Tatiana Portella orienta que as pessoas dos grupos mais vulner\u00e1veis se vacinem contra o v\u00edrus da influenza o quanto antes. <\/strong>Os pesquisadores do InfoGripe refor\u00e7am que a vacina \u00e9 a a\u00e7\u00e3o mais eficaz para prevenir hospitaliza\u00e7\u00f5es e mortes causadas pela doen\u00e7a.\u00a0<\/p>\n<blockquote>\n<p>\u201cAl\u00e9m disso, refor\u00e7amos a import\u00e2ncia do uso de m\u00e1scaras em unidades de sa\u00fade, locais com maior aglomera\u00e7\u00e3o de pessoas e, principalmente, em caso de aparecimento de sintomas de gripe ou resfriado\u201d, alertou a pesquisadora.<\/p>\n<\/blockquote>\n<h2>Casos de SRAG<\/h2>\n<p><strong>O boletim mostra sinal de aumento de casos de SRAG em diversos estados, tanto nas tend\u00eancias de longo prazo (\u00faltimas 6 semanas) quanto nas de curto prazo (\u00faltimas 3 semanas).<\/strong> Esse cen\u00e1rio se deve ao crescimento de SRAG nas crian\u00e7as pequenas, associado principalmente ao VSR, e na popula\u00e7\u00e3o de jovens, adultos e idosos, associado ao v\u00edrus da influenza A.\u00a0<\/p>\n<p>O VSR mant\u00e9m uma incid\u00eancia expressiva tanto de incid\u00eancia quanto de mortalidade por SRAG em crian\u00e7as pequenas. Outros v\u00edrus de destaque nessa faixa et\u00e1ria s\u00e3o o rinov\u00edrus e a influenza A. A influenza A, al\u00e9m de ser a principal causa de mortalidade por SRAG entre os idosos, \u00e9 uma das tr\u00eas principais raz\u00f5es de \u00f3bitos por SRAG em crian\u00e7as pequenas.<\/p>\n<h2>Estados<\/h2>\n<p>Ao todo, 15 das 27 unidades da federa\u00e7\u00e3o apresentam incid\u00eancia de SRAG em n\u00edvel de alerta, risco ou alto risco, com sinal de crescimento na tend\u00eancia de longo prazo: Acre, Amazonas, Bahia, Cear\u00e1, Mato Grosso, Mato Grosso do Sul, Minas Gerais, Paran\u00e1, Rio Grande do Sul, Rio de Janeiro, Rond\u00f4nia, Roraima, Santa Catarina, S\u00e3o Paulo e Tocantins.<\/p>\n<p>Outros oito estados tamb\u00e9m apresentam incid\u00eancia de SRAG em n\u00edveis de alerta, risco ou alto risco, por\u00e9m sem sinal de crescimento de longo prazo: Amap\u00e1, Distrito Federal, Esp\u00edrito Santo, Goi\u00e1s, Maranh\u00e3o, Par\u00e1, Sergipe e Rio Grande do Norte.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2025-05\/gripe-e-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz\">Ag\u00eancia Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O boletim InfoGripe, da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) divulgado nesta quinta-feira (15) faz uma alerta sobre o v\u00edrus da influenza A, causador da gripe, que se tornou a principal causa de mortalidade por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) em idosos e uma das tr\u00eas principais causas de \u00f3bitos entre as crian\u00e7as. Foi registrado tamb\u00e9m um [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-20685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=20685"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/20686"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=20685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=20685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=20685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}