{"id":20174,"date":"2025-05-13T23:24:35","date_gmt":"2025-05-14T02:24:35","guid":{"rendered":"https:\/\/mussicom.com\/casca-de-ovo-em-residuo-de-mandioca-pode-virar-fertilizante\/"},"modified":"2025-05-13T23:24:35","modified_gmt":"2025-05-14T02:24:35","slug":"casca-de-ovo-em-residuo-de-mandioca-pode-virar-fertilizante","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/casca-de-ovo-em-residuo-de-mandioca-pode-virar-fertilizante\/","title":{"rendered":"Casca de ovo em res\u00edduo de mandioca pode virar fertilizante"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"hd80s9wa1h892edh8192\">\n<p>A produ\u00e7\u00e3o de biog\u00e1s e fertilizantes org\u00e2nicos \u00e9 um exemplo do que pode ser feito com esse res\u00edduo.<\/p>\n<p>O aproveitamento de cascas de ovos em res\u00edduo de mandioca pode ser transformado em fonte adicional de renda para os produtores, al\u00e9m de ajudar na redu\u00e7\u00e3o da emiss\u00e3o de gases estufa e na autossufici\u00eancia energ\u00e9tica do pa\u00eds.<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<div class=\"perfmatters-lazy-youtube\" data-src=\"https:\/\/www.youtube.com\/embed\/PV1cCymiMts\" data-id=\"PV1cCymiMts\" data-query=\"feature=oembed\" onclick=\"perfmattersLazyLoadYouTube(this);\">\n<div><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/PV1cCymiMts\/hqdefault.jpg\" alt=\"YouTube video\" width=\"480\" height=\"360\" data-pin-nopin=\"true\" nopin=\"nopin\"\/><\/div>\n<\/div>\n<p><noscript><iframe title=\"A For\u00e7a do Agro, com Joice Maffezzolli - Casca de ovo em res\u00edduo de mandioca pode virar fertilizante\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/PV1cCymiMts?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/noscript>\n<\/div>\n<\/figure>\n<p>Uma pesquisadora da Universidade de Tiradentes estuda o aproveitamento de manipueira e de cascas de ovo para a produ\u00e7\u00e3o de biog\u00e1s e res\u00edduos s\u00f3lidos, como fertilizante org\u00e2nico.<\/p>\n<p>Em <strong>A For\u00e7a do Agro<\/strong> desta ter\u00e7a-feira, 13, o espectador vai descobrir como \u00e9 poss\u00edvel transformar cascas de ovo em insumos e seus benef\u00edcios.<\/p>\n<h2 class=\"wp-block-heading wp-embed-aspect-16-9 wp-has-aspect-ratio\">A For\u00e7a do Agro<\/h2>\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\">Com uma crescente necessidade de pr\u00e1ticas mais sustent\u00e1veis, o agroneg\u00f3cio busca inovar constantemente para aprimorar a produtividade e minimizar impactos ambientais.<\/p>\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\">Em <strong>A For\u00e7a do Agro<\/strong> s\u00e3o apresentados os principais t\u00f3picos que fazem o agro ser t\u00e3o especial para o <strong>Brasil<\/strong> e para o mundo.<\/p>\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\">De segunda a sexta-feira, o programa leva informa\u00e7\u00e3o e conhecimento ao internauta e tem o papel de conectar o campo \u00e0 cidade, mas de uma maneira leve e descontra\u00edda.<\/p>\n<p><strong>+ Leia mais not\u00edcias de Agroneg\u00f3cio em Oeste<\/strong><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/revistaoeste.com\/agronegocio\/casca-de-ovo-em-residuo-de-mandioca-pode-virar-fertilizante\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A produ\u00e7\u00e3o de biog\u00e1s e fertilizantes org\u00e2nicos \u00e9 um exemplo do que pode ser feito com esse res\u00edduo. O aproveitamento de cascas de ovos em res\u00edduo de mandioca pode ser transformado em fonte adicional de renda para os produtores, al\u00e9m de ajudar na redu\u00e7\u00e3o da emiss\u00e3o de gases estufa e na autossufici\u00eancia energ\u00e9tica do pa\u00eds. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[53],"tags":[],"class_list":["post-20174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=20174"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/20174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/20175"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=20174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=20174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=20174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}