{"id":19884,"date":"2025-05-12T21:31:28","date_gmt":"2025-05-13T00:31:28","guid":{"rendered":"https:\/\/mussicom.com\/antes-do-conclave-frei-betto-descartou-um-papa-dos-eua\/"},"modified":"2025-05-12T21:31:28","modified_gmt":"2025-05-13T00:31:28","slug":"antes-do-conclave-frei-betto-descartou-um-papa-dos-eua","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/antes-do-conclave-frei-betto-descartou-um-papa-dos-eua\/","title":{"rendered":"Antes do conclave, Frei Betto descartou um papa dos EUA"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"hd80s9wa1h892edh8192\">\n<p>No dia anterior \u00e0 vota\u00e7\u00e3o que elegeu o cardeal norte-americano Robert Francis Prevost como papa Le\u00e3o XIV, o te\u00f3logo Frei Betto afirmou que via como \u201cmuito, muito remota\u201d a possibilidade de um papa dos Estados Unidos. A declara\u00e7\u00e3o foi dada em entrevista ao portal de esquerda Brasil de Fato na \u00faltima quarta-feira, 7.<\/p>\n<p>\u201cO que eu conhe\u00e7o da Igreja, <em>[me leva a]<\/em> descartar inteiramente qualquer cardeal dos EUA\u201d, disse o dominicano. Ele relatou ter ouvido de um cardeal com experi\u00eancia em dois conclaves que, \u201ccomo eles <em>[os norte-americanos]<\/em> s\u00e3o os mais ricos da Igreja e os mais arrogantes, h\u00e1 uma rejei\u00e7\u00e3o a eles muito forte\u201d.<\/p>\n<p>+\u00a0<strong>Leia mais not\u00edcias de\u00a0Mundo\u00a0em Oeste<\/strong><\/p>\n<p>Betto ainda mencionou um epis\u00f3dio com o presidente Donald Trump como agravante do desconforto com os norte-americanos. \u201cEssa rejei\u00e7\u00e3o deve ter aumentado no momento em que o Trump deu um tiro no p\u00e9 ao divulgar aquela foto dele fantasiado de Papa\u201d, avaliou. \u201cIsso causou profunda indigna\u00e7\u00e3o na Igreja, inclusive por parte dos conservadores.\u201d<\/p>\n<p>Apesar da previs\u00e3o, os cardeais reunidos no conclave optaram por um nome dos EUA e romperam com a expectativa tra\u00e7ada pelo te\u00f3logo. Prevost nasceu em Chicago, em 1955, e at\u00e9 a elei\u00e7\u00e3o exercia fun\u00e7\u00f5es importantes na C\u00faria Romana, como a chefia do Dicast\u00e9rio para os Bispos.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DJXwKqKvMYr\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/>\n<p>Na entrevista, Betto havia apostado na possibilidade de vit\u00f3ria de nomes italianos ou do cardeal filipino Luis Antonio Tagle, mas ressaltou que o \u201co \u00fanico problema que conta contra ele \u00e9 que ele \u00e9 muito novo\u201d, ao observar que os cardeais poderiam evitar um pontificado longo como o de Jo\u00e3o Paulo II, que durou 26 anos.<\/p>\n<p>Para o frei, os africanos tamb\u00e9m estavam fora do p\u00e1reo, apesar de reivindicarem a lideran\u00e7a com base na expans\u00e3o do catolicismo no continente: \u201cS\u00e3o todos, sem exce\u00e7\u00e3o, conservadores\u201d, lamentou. \u201cAcho muito dif\u00edcil que o Conclave venha a eleger um cardeal que vai criar uma ruptura com a linha do Francisco.\u201d<\/p>\n<p><related-posts class=\"border-y border-gray-300 py-5\"><\/p>\n<h2 class=\"!text-2xl text-black font-primary font-semibold leading-none mb-3\">\n    Leia mais:<br \/>\n  <\/h2>\n<p><\/related-posts><\/p>\n<h2 class=\"wp-block-heading\">Frei Betto apostava em um papa italiano<\/h2>\n<p>Ele tamb\u00e9m apostou na possibilidade de retorno da hegemonia italiana e citou os cardeais Pietro Parolin e Matteo Zuppi como poss\u00edveis eleitos. Zuppi, que preside a Confer\u00eancia Episcopal Italiana, era, segundo ele, o mais alinhado com a linha de Francisco, \u201ctanto nas quest\u00f5es de costumes quanto nas quest\u00f5es sociais, clim\u00e1ticas, etc.\u201d.<\/p>\n<p>Sobre os bastidores da escolha, Betto alertou que o processo seria mais demorado do que os conclaves anteriores. Enquanto as elei\u00e7\u00f5es de Bento XVI e <strong>Francisco<\/strong> duraram 48 horas, ele previu algo entre \u201ctr\u00eas ou quatro dias\u201d, por causa das dificuldades de alcan\u00e7ar o qu\u00f3rum de dois ter\u00e7os.<\/p>\n<p>O cen\u00e1rio, segundo ele, era marcado por fragmenta\u00e7\u00e3o: \u201cMuitos s\u00e3o estranhos uns para outros, de modo que \u00e9 absolutamente imprevis\u00edvel\u201d, considerou. No entanto, o tempo de dura\u00e7\u00e3o do processo de escolha de Prevost foi igual aos de seus antecessores.<\/p>\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><picture><source data-srcset=\"https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH.jpg.webp 1923w, https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH-300x199.jpg.webp 300w, https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH-150x100.jpg.webp 150w\" data-sizes=\"(max-width: 1923px) 100vw, 1923px\" type=\"image\/webp\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1923\" height=\"1278\" src=\"https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH.jpg\" alt=\"Papa Le\u00e3o XIV logo ap\u00f3s ser eleito | Foto: REUTERS\/Yara Nardi\/File Photo\" class=\"wp-image-1987754\" style=\"width:770px;height:auto\" srcset=\"https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH.jpg 1923w, https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH-300x199.jpg 300w, https:\/\/medias.revistaoeste.com\/wp-content\/uploads\/2025\/05\/2025-05-09T140527Z_1794690464_RC2UDEAZZZ1V_RTRMADP_3_POPE-LEO-PATH-150x100.jpg 150w\" sizes=\"(max-width: 1923px) 100vw, 1923px\" data-eio=\"p\"\/><\/source><\/picture><figcaption class=\"wp-element-caption\">Papa Le\u00e3o XIV logo depois de ser eleito | Foto: REUTERS\/Yara Nardi\/File Photo<\/figcaption><\/figure>\n<p>Na ocasi\u00e3o, o frei destacou a influ\u00eancia dos cardeais com mais de 80 anos, que, embora sem direito a voto, permanecem presentes nas discuss\u00f5es: \u201c\u00c0s vezes eu escuto na imprensa, leio, que s\u00f3 os 133 decidem\u201d, disse. \u201c<em>[Os decanos]<\/em> n\u00e3o decidem pelo voto, mas os demais convivem com eles ali dentro todo o per\u00edodo que durar o conclave.\u201d<\/p>\n<p>A entrevista ainda abordou a representatividade latino-americana. O te\u00f3logo informou que o Brasil contava com oito cardeais \u2014 sete eleitores \u2014 no conclave e destacou Leonardo Steiner como o mais alinhado com o papa Francisco.<\/p>\n<p>\u201c\u00c9 uma pessoa que conhe\u00e7o pessoalmente, acompanho h\u00e1 muitos anos a sua atividade pastoral, um defensor intransigente dos povos origin\u00e1rios da Amaz\u00f4nia, do equil\u00edbrio ambiental\u201d, elogiou o religioso. \u201cQuando denuncia as mazelas sociais, ele aponta as causas.\u201d<\/p>\n<h2 class=\"wp-block-heading\">As rea\u00e7\u00f5es \u00e0 elei\u00e7\u00e3o de Prevost<\/h2>\n<p>Ainda que o novo papa tenha nascido nos EUA, Betto classificou Le\u00e3o XIV como um \u201cperuano de cora\u00e7\u00e3o\u201d. \u201cEle ter exercido todo o seu minist\u00e9rio, como sacerdote e como bispo no Peru, me d\u00e1 muita esperan\u00e7a nele, que vai continuar a linha de Francisco\u201d, disse o religioso em entrevista ao <em>Estado de Minas<\/em>.<\/p>\n<p>Ainda ao jornal mineiro, Betto observou que a escolha do nome papal tamb\u00e9m possui forte carga simb\u00f3lica: \u201cEle adotou o nome Le\u00e3o XIV, o segmento de Le\u00e3o XIII, que foi o papa da reforma trabalhista, o papa que fez a enc\u00edclica <em><strong>Rerum Novarum<\/strong><\/em> <em>[\u2026]<\/em> em que abordava a favor dos trabalhadores, a rela\u00e7\u00e3o entre trabalhadores e empres\u00e1rios\u201d.<\/p>\n<p>A revista <em>F\u00f3rum<\/em> tamb\u00e9m ouviu o frei, que confessou sua surpresa com a elei\u00e7\u00e3o de Prevost. Segundo ele, o hist\u00f3rico latinoamericano de Prevost ameniza a rejei\u00e7\u00e3o aos cardeais norte-americanos.<\/p>\n<p>A entrevista \u00e0 <em>F\u00f3rum<\/em> tamb\u00e9m revelou um olhar cr\u00edtico ao primeiro discurso de Le\u00e3o XIV. Frei Betto declarou estar \u201cum pouco decepcionado\u201d e que esperava \u201cum serm\u00e3o delineando caminhos para a maior inser\u00e7\u00e3o da igreja no mundo\u201d, mas encontrou uma fala \u201cmais centrada na f\u00e9 do que no amor e mais centrada na piedade do que na justi\u00e7a\u201d.<\/p>\n<p><strong>Leia tamb\u00e9m:\u00a0\u201cF\u00e9 sem fronteiras\u201d, artigo de Ana Paula Henkel publicado na Edi\u00e7\u00e3o 239 da Revista Oeste<\/strong><\/p>\n<\/p><\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/>Fonte: <a href=\"https:\/\/revistaoeste.com\/mundo\/internet-resgata-video-em-que-frei-betto-descarta-chance-de-um-papa-dos-eua\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia anterior \u00e0 vota\u00e7\u00e3o que elegeu o cardeal norte-americano Robert Francis Prevost como papa Le\u00e3o XIV, o te\u00f3logo Frei Betto afirmou que via como \u201cmuito, muito remota\u201d a possibilidade de um papa dos Estados Unidos. A declara\u00e7\u00e3o foi dada em entrevista ao portal de esquerda Brasil de Fato na \u00faltima quarta-feira, 7. \u201cO que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-19884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/19884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=19884"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/19884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/19885"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=19884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=19884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=19884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}