{"id":19369,"date":"2025-05-10T10:39:46","date_gmt":"2025-05-10T13:39:46","guid":{"rendered":"https:\/\/mussicom.com\/tentar-encaixar-leao-xiv-numa-caixinha-politica-e-erro\/"},"modified":"2025-05-10T10:39:46","modified_gmt":"2025-05-10T13:39:46","slug":"tentar-encaixar-leao-xiv-numa-caixinha-politica-e-erro","status":"publish","type":"post","link":"https:\/\/mussicom.com\/noticias\/tentar-encaixar-leao-xiv-numa-caixinha-politica-e-erro\/","title":{"rendered":"Tentar encaixar Le\u00e3o XIV numa caixinha pol\u00edtica \u00e9 erro"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">A escolha do papa Le\u00e3o XIV surpreendeu quem esperava uma figura facilmente rotul\u00e1vel, que pudesse ser classificada rapidamente como progressista ou conservadora. Mas a Igreja Cat\u00f3lica, com seus dois mil anos de hist\u00f3ria, n\u00e3o costuma escolher com base nos clich\u00eas de rede social. E talvez essa seja justamente a li\u00e7\u00e3o mais urgente deste momento.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Le\u00e3o XIV foi chamado de \u201cpapa isent\u00e3o\u201d, um r\u00f3tulo que diz mais sobre quem o profere do que sobre o pr\u00f3prio papa. Fan\u00e1ticos pol\u00edticos e parte da imprensa se dividem. Ora o colocam como progressista, ora como conservador. Voc\u00ea ver\u00e1 gente dizendo que o papa \u00e9 de esquerda e tamb\u00e9m que \u00e9 de direita.<\/p>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">Antes mesmo da elei\u00e7\u00e3o, o ent\u00e3o cardeal Robert Francis Prevost era conhecido por algo raro na era do confronto: a capacidade de mediar. Construiu pontes dentro da Igreja entre alas que h\u00e1 tempos se enxergam como rivais. Seu lema episcopal, <em>\u201cIn Illo uno unum\u201d<\/em>, retirado de um serm\u00e3o de Santo Agostinho, resume com precis\u00e3o seu olhar para a f\u00e9: \u201cembora sejamos muitos, no \u00fanico Cristo somos um\u201d.<\/p>\n<blockquote class=\"postQuote_post-quote-container__KXTpH\">\n<div class=\"postQuote_post-quote-content__wp4c4\">\n<p>N\u00e3o espere de Le\u00e3o XIV slogans ideol\u00f3gicos. Espere uma lideran\u00e7a que, fiel ao Evangelho, seja capaz de promover a justi\u00e7a sem \u00f3dio e a verdade sem arrog\u00e2ncia. Talvez o novo papa esteja nos ensinando, com seu exemplo, que o mundo n\u00e3o precisa de mais extremistas, precisa de mais mediadores<\/p>\n<\/div>\n<\/blockquote>\n<p class=\"postParagraph_post-paragraph-innerHtml__Q5vwc\">Como \u00e9 t\u00edpico do nosso tempo, h\u00e1 na internet cat\u00f3licos que gostam de julgar e maldizer reclamando do Santo Padre, alguns querem at\u00e9 ensinar B\u00edblia a ele ou formas de escolher aos cardeais do Conclave. Surgem tamb\u00e9m os ateus te\u00f3logos, formados na universidade das redes sociais, que citam passagens da B\u00edblia de forma utilit\u00e1ria, como quem descobre agora que \u201cos mornos ser\u00e3o vomitados\u201d. Em vez de enxergar a profundidade de uma escolha eclesial, preferem aplicar filtros de milit\u00e2ncia secular a uma institui\u00e7\u00e3o que j\u00e1 atravessou imp\u00e9rios, revolu\u00e7\u00f5es e modismos ideol\u00f3gicos. E \u00e9 a\u00ed que precisamos parar e pensar: ser\u00e1 que a nossa leitura sobre a polariza\u00e7\u00e3o est\u00e1 errada?<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">Le\u00e3o XIV n\u00e3o representa a neutralidade nem a tibieza. Ele n\u00e3o finge que n\u00e3o existem conflitos, ele se recusa a ser sugado por eles. A grande polariza\u00e7\u00e3o do nosso tempo n\u00e3o \u00e9 entre conservadores e progressistas, esquerda e direita. \u00c9 entre intolerantes e mediadores. O intolerante \u00e9 aquele que quer tudo do seu jeito. Que usa qualquer arma, da difama\u00e7\u00e3o \u00e0 intimida\u00e7\u00e3o, para aniquilar advers\u00e1rios. Que perdoa todas as imoralidades e perversidade de quem est\u00e1 do seu lado, enquanto aponta os erros dos opositores. O intolerante pode se vestir de qualquer ideologia: direita, esquerda, progressista ou conservador. A intoler\u00e2ncia \u00e9 um modo de existir, n\u00e3o uma opini\u00e3o pol\u00edtica.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">O mediador, por sua vez, \u00e9 o que compreende os limites do humano. O que sabe que todos t\u00eam convic\u00e7\u00f5es, mas que a conviv\u00eancia exige regras, respeito e escuta. O mediador n\u00e3o abre m\u00e3o da sua f\u00e9 ou da sua raz\u00e3o, ele abre espa\u00e7o. Ele n\u00e3o relativiza o que cr\u00ea, ele compartilha. O mediador n\u00e3o se omite. Ele constr\u00f3i. \u00c9 esse o esp\u00edrito de Le\u00e3o XIV. Um papa que conhece a doutrina e a hist\u00f3ria da Igreja, entendendo que a miss\u00e3o crist\u00e3 \u00e9 unir o rebanho, n\u00e3o dividi-lo em trincheiras ideol\u00f3gicas. Sua elei\u00e7\u00e3o mostra que a Igreja n\u00e3o se orienta pela l\u00f3gica de curtidas ou cancelamentos. Ela se orienta por algo mais duradouro: a miss\u00e3o de ser sal e luz do mundo, mesmo quando o mundo exige gritaria.<\/p>\n<div class=\"postViewMore_post-view-more-container___5wai\" data-mrf-recirculation=\"Post - Veja tamb\u00e9m\">\n<p class=\"gp-styles-module-size-small-afeYRa gp-styles-module-font-family2-afeYRa gp-styles-module-color-secondary-afeYRa gp-styles-module-weight-bold-afeYRa\">VEJA TAMB\u00c9M:<\/p>\n<ul class=\"postViewMore_post-view-more-list__CU_CE\">\n<li class=\"postViewMore_post-view-more-item__2MzRb\"><span class=\"postViewMore_post-view-more-link-icon___stPC\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" fill=\"none\"\/><g transform=\"translate(3 3)\"><path d=\"M22.5,15l3.4,3.4-3.4,3.4\" transform=\"translate(-15.896 -11.793)\" fill=\"none\" stroke=\"#717171\" stroke-linecap=\"round\" stroke-width=\"1.4\"\/><path d=\"M6,6v4.2a2.452,2.452,0,0,0,2.5,2.4H16\" transform=\"translate(-6 -6)\" fill=\"none\" stroke=\"#717171\" stroke-linecap=\"round\" stroke-width=\"1.4\"\/><\/g><\/svg><\/span><span class=\"postViewMore_post-view-more-link-text__hO_kM\">Por que Lula recebeu sindicalistas mas n\u00e3o os aposentados v\u00edtimas da fraude no INSS?<\/span><\/li>\n<\/ul>\n<\/div>\n<p class=\"postParagraph_post-paragraph__juWZN\">Tentar encaixar Le\u00e3o XIV numa caixinha pol\u00edtica \u00e9 perda de tempo. Ele n\u00e3o est\u00e1 ali para agradar a um lado nem para apaziguar militantes. Est\u00e1 ali para pastorear. E o pastoreio, como nos lembra o pr\u00f3prio Cristo, exige mais do que bravura: exige humildade e miseric\u00f3rdia. N\u00e3o por acaso, o novo papa afirmou em sua homilia de posse que \u201ca miseric\u00f3rdia n\u00e3o \u00e9 um ornamento da f\u00e9, mas sua subst\u00e2ncia\u201d.<\/p>\n<p class=\"postParagraph_post-paragraph__juWZN\">N\u00e3o espere de Le\u00e3o XIV slogans ideol\u00f3gicos. Espere uma lideran\u00e7a que, fiel ao Evangelho, seja capaz de promover a justi\u00e7a sem \u00f3dio e a verdade sem arrog\u00e2ncia. Talvez o novo papa esteja nos ensinando, com seu exemplo, que o mundo n\u00e3o precisa de mais extremistas, precisa de mais mediadores. A Igreja n\u00e3o se molda \u00e0s disputas partid\u00e1rias do tempo presente. Ela as atravessa. E o papa Le\u00e3o XIV \u00e9 mais uma prova disso.<\/p>\n<\/div>\n<p><br \/>\n<br \/>Fonte: <a href=\"https:\/\/www.gazetadopovo.com.br\/vozes\/cidadania-digital\/papa-leao-xiv-caixinha-politica-erro-perda-de-tempo\/\">Revista Oeste<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A escolha do papa Le\u00e3o XIV surpreendeu quem esperava uma figura facilmente rotul\u00e1vel, que pudesse ser classificada rapidamente como progressista ou conservadora. Mas a Igreja Cat\u00f3lica, com seus dois mil anos de hist\u00f3ria, n\u00e3o costuma escolher com base nos clich\u00eas de rede social. E talvez essa seja justamente a li\u00e7\u00e3o mais urgente deste momento. Le\u00e3o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-19369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/19369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/comments?post=19369"}],"version-history":[{"count":0,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/posts\/19369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media\/19219"}],"wp:attachment":[{"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/media?parent=19369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/categories?post=19369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussicom.com\/noticias\/wp-json\/wp\/v2\/tags?post=19369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}